{"id":5223,"date":"2015-10-20T08:00:03","date_gmt":"2015-10-20T08:00:03","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=4629"},"modified":"2020-04-11T07:16:19","modified_gmt":"2020-04-11T07:16:19","slug":"dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2","status":"publish","type":"post","link":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/","title":{"rendered":"Dissolution d&#039;une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)"},"content":{"rendered":"<p style=\"text-align: justify;\">Les articles 360 \u00e0 370 de la Ley de Sociedades de Capital (LSC) r\u00e9gulent la dissolution des soci\u00e9t\u00e9s de capitaux comme la soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e (S.A.R.L, Sociedad Limitada, S.L.).<!--moreDissolution d'une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)--><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Dissolution de la S.A.R.L pour difficult\u00e9s \u00e9conomiques<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff6600;\"><strong>Dissolution pour accumulation des pertes<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Cette cause survient lorsqu\u2019une soci\u00e9t\u00e9 comptabilise des pertes dont le montant r\u00e9duit le patrimoine net[1] de la soci\u00e9t\u00e9 \u00e0 une valeur inf\u00e9rieure \u00e0 la moiti\u00e9 de son capital social. Cette dissolution n\u2019est pas automatique, elle requiert \u00a0l\u2019accord de l\u2019assembl\u00e9e G\u00e9n\u00e9rale des actionnaires.<\/p>\n<p style=\"text-align: justify;\">Il est bon de pr\u00e9ciser qu\u2019une telle dissolution pour accumulation des pertes peut \u00eatre \u00e9vit\u00e9e gr\u00e2ce \u00e0 4 m\u00e9canismes\u00a0:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Augmentation du capital en quantit\u00e9 suffisante pour r\u00e9tablir l\u2019\u00e9quilibre entre le patrimoine net et le capital social<\/li>\n<li style=\"text-align: justify;\">R\u00e9duction du capital social pour absorber les pertes<\/li>\n<li style=\"text-align: justify;\">R\u00e9duction et augmentation simultan\u00e9es du capital social<\/li>\n<li style=\"text-align: justify;\">Apport des associ\u00e9s pour compenser les pertes<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>R\u00e9duction du capital en dessous du seuil l\u00e9gal minimal<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L\u2019article 363.1 f) de la LSC) pr\u00e9voit la dissolution obligatoire de la S.A.R.L dont le capital social serait r\u00e9duit \u00e0 un niveau inf\u00e9rieur au seuil l\u00e9gal minimal de 3000\u20ac.<\/p>\n<p style=\"text-align: justify;\">Une telle r\u00e9duction patrimoniale peut \u00eatre la cons\u00e9quence\u00a0:<\/p>\n<ul>\n<li style=\"text-align: justify;\">de la sortie ou de l\u2019exclusion d\u2019un ou plusieurs actionnaires pour des raisons \u00e9tablies par la loi (separaci\u00f3n o exclusi\u00f3n de socios por causas establecidas legalmente)<\/li>\n<li style=\"text-align: justify;\">de l\u2019acquisition d\u2019actions par la soci\u00e9t\u00e9 \u00e0 des fins d\u2019amortissement<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">De m\u00eame que pour la dissolution en raison de l\u2019accumulation de pertes, la dissolution pour r\u00e9duction du capital social en dessous du seuil l\u00e9gal minimal peut \u00eatre \u00e9vit\u00e9e par l\u2019augmentation du capital social de la S.A.R.L, ou par sa transformation en une autre forme de soci\u00e9t\u00e9.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Dissolution de la S.A.R.L en raison du comportement de ses associ\u00e9s<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff6600;\"><strong>Dissolution de la S.A.R.L en raison d\u2019un accord entre ses associ\u00e9s\u00a0: d\u00e9cision d\u2019assembl\u00e9e des actionnaires<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">L\u2019exercice du principe de l\u2019autonomie de la volont\u00e9 permet aux associ\u00e9s de dissoudre la soci\u00e9t\u00e9 sans raisons apparentes, au travers du vote favorable de plus de la moiti\u00e9 des parts d\u00e9tenues par les actionnaires a lors d\u2019une assembl\u00e9e g\u00e9n\u00e9rale (la dissolution doit figurer \u00e0 l\u2019ordre du jour de la convocation de l\u2019AG). La dissolution, une fois vot\u00e9e, doit faire l\u2019objet d\u2019un acte authentique et d\u2019une inscription \u00a0au Registre du Commerce et des Soci\u00e9t\u00e9s (Registro Mercantil).<\/p>\n<h3 style=\"text-align: justify;\"><span style=\"color: #ff6600;\"><strong>Dissolution de la S.A.R.L en raison d\u2019un d\u00e9saccord entre ses associ\u00e9s\u00a0: paralysie du fonctionnement de la soci\u00e9t\u00e9<\/strong><\/span><\/h3>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Le d\u00e9saccord entre les associ\u00e9s peut parfois entrainer une paralysie totale du fonctionnement de l\u2019entreprise.<\/p>\n<p style=\"text-align: justify;\">Pour que la \u00a0paralysie entra\u00eene la dissolution de la soci\u00e9t\u00e9, elle doit \u00eatre continue et doit bloquer, de mani\u00e8re significative, la prise de d\u00e9cision. La dissolution sera alors obligatoirement judiciaire \u00e9tant donn\u00e9 que les organes de la soci\u00e9t\u00e9 ne parviennent \u00a0pas \u00e0 trouver d\u2019accord.<\/p>\n<p style=\"text-align: justify;\">Cependant, la dissolution peut \u00eatre \u00e9vit\u00e9e s\u2019il \u00a0est mis un terme aux causes de cette paralysie.<\/p>\n<p style=\"text-align: justify;\"><strong>Cl\u00e9ment-Henri Girardot &amp; Nicol\u00e1s Melchior<\/strong><br \/>\n<a title=\"Mariscal Abogados, Avocats Madrid, Espagne\" href=\"http:\/\/www.mariscal-abogados.eu\/categoria\/investissement-et-residence-en-espagne\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mariscal Abogados, Avocats francophones en Espagne<\/strong><\/a><\/p>\n<h2><strong><strong><a title=\"Eurojuris Espa\u00f1a, international network of law firms in Spain\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Eurojuris Espa\u00f1a<\/em><\/a><\/strong><\/strong><strong><strong><a title=\"Eurojuris Espa\u00f1a, international network of law firms in Spain\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\" target=\"_blank\" rel=\"noopener noreferrer\"><em>, r\u00e9seau espagnol inernational de cabinet d\u2019avocats<\/em><\/a><\/strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<hr \/>\n<p style=\"text-align: justify;\">[1] Le patrimoine net constitue le patrimoine r\u00e9el d\u2019une entreprise \u00e0 un moment donn\u00e9, c\u2019est-\u00e0-dire, les biens de l\u2019entreprise moins les dettes et engagements financiers contract\u00e9s par celle-ci.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Parmi les diff\u00e9rents cas de dissolution d\u2019une SARL pr\u00e9vus en Espagne, certains s\u2019appuient sur des motifs \u00e9conomiques (accumulation de pertes, r\u00e9duction du capital social en dessous d\u2019un seuil l\u00e9gal, etc.) et d\u2019autres peuvent reposer sur le comportement des associ\u00e9s (paralysie de la soci\u00e9t\u00e9, accord sur la dissolution, etc.).<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[258],"tags":[],"class_list":["post-5223","post","type-post","status-publish","format-standard","hentry","category-articles-juridiques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dissolution de la soci\u00e9t\u00e9 SARL en Espagne<\/title>\n<meta name=\"description\" content=\"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dissolution de la soci\u00e9t\u00e9 SARL en Espagne\" \/>\n<meta property=\"og:description\" content=\"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2015-10-20T08:00:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:16:19+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Dissolution d&#039;une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)\",\"datePublished\":\"2015-10-20T08:00:03+00:00\",\"dateModified\":\"2020-04-11T07:16:19+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/\"},\"wordCount\":635,\"articleSection\":[\"Articles juridiques\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/\",\"name\":\"Dissolution de la soci\u00e9t\u00e9 SARL en Espagne\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2015-10-20T08:00:03+00:00\",\"dateModified\":\"2020-04-11T07:16:19+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dissolution d&#039;une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dissolution de la soci\u00e9t\u00e9 SARL en Espagne","description":"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/","og_locale":"en_US","og_type":"article","og_title":"Dissolution de la soci\u00e9t\u00e9 SARL en Espagne","og_description":"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2015-10-20T08:00:03+00:00","article_modified_time":"2020-04-11T07:16:19+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Dissolution d&#039;une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)","datePublished":"2015-10-20T08:00:03+00:00","dateModified":"2020-04-11T07:16:19+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/"},"wordCount":635,"articleSection":["Articles juridiques"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/","name":"Dissolution de la soci\u00e9t\u00e9 SARL en Espagne","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2015-10-20T08:00:03+00:00","dateModified":"2020-04-11T07:16:19+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"La loi espagnole pr\u00e9voit diff\u00e9rents cas de dissolution d\u2019une SARL, pour des motifs \u00e9conomiques ou \u00e0 cause du comportement des associ\u00e9s.","breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/dissolution-dune-societe-a-responsabilite-limitee-en-espagne-sarl-2\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Dissolution d&#039;une soci\u00e9t\u00e9 \u00e0 responsabilit\u00e9 limit\u00e9e en Espagne (SARL)"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5223","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5223"}],"version-history":[{"count":2,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5223\/revisions"}],"predecessor-version":[{"id":6554,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5223\/revisions\/6554"}],"wp:attachment":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5223"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5223"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5223"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}