{"id":5039,"date":"2016-04-11T08:00:39","date_gmt":"2016-04-11T08:00:39","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=5039"},"modified":"2020-04-11T07:15:55","modified_gmt":"2020-04-11T07:15:55","slug":"le-role-de-lagent-commercial-en-espagne","status":"publish","type":"post","link":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/","title":{"rendered":"Le r\u00f4le de l\u2019agent commercial en Espagne"},"content":{"rendered":"<p style=\"text-align: justify;\">Le r\u00f4le de l\u2019agent commercial, selon ses diverses interpr\u00e9tations l\u00e9gales et commerciales, peut \u00eatre source de confusion. Il est donc essentiel de connaitre la signification du terme \u00ab\u00a0agent commercial\u00a0\u00bb et de bien comprendre le r\u00f4le de l\u2019agent dans les exportations.<!--moreLe r\u00f4le de l\u2019agent commercial en Espagne--><\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Qu\u2019est-ce qu\u2019un agent commercial ?<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Un agent commercial est un professionnel responsable en permanence de la promotion, de la n\u00e9gociation ou de la gestion des activit\u00e9s commerciales\u00a0 pour le compte et au nom de plusieurs entreprises, dans une zone d\u00e9termin\u00e9e (dans le m\u00eame pays, et \u00e0 l\u2019international), le tout en l\u2019\u00e9change d\u2019une r\u00e9mun\u00e9ration.<\/p>\n<p style=\"text-align: justify;\">Dans le cadre de ses fonctions, l\u2019agent commercial peut lier l\u2019entreprise pour le compte de laquelle il agit, dans ce cas c\u2019est l\u2019entreprise et non l\u2019agent qui est responsable du succ\u00e8s des op\u00e9rations.<\/p>\n<p style=\"text-align: justify;\">Par cons\u00e9quent, les agents commerciaux ne sont pas des employ\u00e9s, mais des professionnels ind\u00e9pendants avec un statut de travailleur ind\u00e9pendant, li\u00e9 \u00e0 l\u2019employeur par un contrat de mandat. Ainsi, la client\u00e8le est consid\u00e9r\u00e9e appartenir \u00e0 l\u2019agent et non \u00e0 l\u2019entreprise. En aucun cas l\u2019agent acquiert la propri\u00e9t\u00e9 des marchandises sauf si l\u2019agent devient un consommateur ou, en dernier ressort, un distributeur du produit principal de l\u2019entreprise.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>R\u00e9glementation juridique<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">En Espagne, la l\u00e9gislation sur les agents commerciaux est \u00e9tablie par la loi 12\/1992 du 27 mai 1992 sur le contrat d\u2019agence, inspir\u00e9e par la directive 86\/653 \/ CEE du 18 d\u00e9cembre 1986 portant coordination des droits des Etats Membres concernant les agents commerciaux ind\u00e9pendants. N\u00e9anmoins, la Directive laisse une large libert\u00e9 \u00e0 certains aspects du contrat d\u2019agence, qui autorise des diff\u00e9rences l\u00e9gislatives importantes sur le r\u00f4le de l\u2019agent commercial au sein de la Communaut\u00e9 Europ\u00e9enne.<\/p>\n<p style=\"text-align: justify;\">Un contrat d\u2019agence est le moyen par lequel une personne physique ou morale adopte une position stable et permanente d\u2019agent commercial li\u00e9 \u00e0 une entreprise. D\u2019un point de vue international, il n\u2019y a pas d\u2019uniformit\u00e9 juridique r\u00e9glementant les contrats d\u2019agence, rendant n\u00e9cessaire de pr\u00e9ciser dans le contrat la loi applicable et utile \u00e0 l\u2019interpr\u00e9tation du contrat.<\/p>\n<p style=\"text-align: justify;\">Le contrat d\u2019agence doit pr\u00e9ciser\u00a0:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Une description du pouvoir et de l\u2019autorit\u00e9 de l\u2019agent commercial<\/li>\n<li style=\"text-align: justify;\">Toutes les activit\u00e9s relatives aux fonctions de l\u2019agent<\/li>\n<li style=\"text-align: justify;\">La dur\u00e9e du contrat<\/li>\n<li style=\"text-align: justify;\">Le domaine particulier dans lequel l\u2019agent d\u00e9veloppe son activit\u00e9<\/li>\n<li style=\"text-align: justify;\">Conform\u00e9ment au Code du Commerce espagnol, le contrat d\u2019agence devrait \u00eatre enregistr\u00e9 pour \u00eatre opposable aux tiers.<\/li>\n<\/ul>\n<p><span style=\"color: #000080;\"><strong>Fonctions<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">Dans l\u2019activit\u00e9 professionnelle de l\u2019agent, l\u2019agent commercial doit agir dans l\u2019int\u00e9r\u00eat de l\u2019entreprise ou des entreprises qu\u2019il repr\u00e9sente, g\u00e9n\u00e9ralement en r\u00e9alisant les fonctions suivantes\u00a0:<\/p>\n<ul>\n<li style=\"text-align: justify;\">Informer l\u2019entreprise de la situation dans le march\u00e9 vis\u00e9\n<ul>\n<li style=\"text-align: justify;\">statistiques et marketing sur la solvabilit\u00e9 des parties avec qui il existe des op\u00e9rations en cours de conclusion ou d\u2019ex\u00e9cution.<\/li>\n<li style=\"text-align: justify;\">recevoir pour le compte de l\u2019entreprise tout type de plaintes de tiers sur les op\u00e9rations soutenues, m\u00eame si elles n\u2019ont pas \u00e9t\u00e9 conclues.<\/li>\n<li style=\"text-align: justify;\">r\u00e9aliser une comptabilit\u00e9 ind\u00e9pendante pour l\u2019entreprise pour laquelle l\u2019agent travaille.<\/li>\n<li style=\"text-align: justify;\">promouvoir les produits de l\u2019entreprise<\/li>\n<li style=\"text-align: justify;\">d\u00e9velopper son ou ses activit\u00e9s conform\u00e9ment aux instructions appropri\u00e9es re\u00e7ues de l\u2019entreprise, sous r\u00e9serve que cela n\u2019affecte pas l\u2019ind\u00e9pendance de l\u2019agent.<\/li>\n<\/ul>\n<\/li>\n<li style=\"text-align: justify;\">N\u00e9gocier les transactions de vente avec les consommateurs<\/li>\n<li style=\"text-align: justify;\">Conclure des op\u00e9rations commerciales, laissant l\u2019entreprise responsable<\/li>\n<\/ul>\n<p style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>L\u2019autorisation:<\/strong><\/span><\/p>\n<p style=\"text-align: justify;\">L\u2019autorisation (octroi d\u2019une licence) est obligatoire dans certains pays, comme en Espagne et en France. En Espagne, l\u2019agent commercial ne pourra pas exercer ses fonctions avant d\u2019\u00eatre enregistr\u00e9 aupr\u00e8s de l\u2019institution reconnue de la province dans laquelle il vit.<\/p>\n<p style=\"text-align: justify;\">L\u2019enregistrement aupr\u00e8s de l\u2019association professionnelle est obligatoire pour ceux qui exercent leurs fonctions en Espagne, ind\u00e9pendamment de leur nationalit\u00e9, lorsqu\u2019ils agissent pour le compte d\u2019entreprises \u00e9trang\u00e8res, cela est aussi valable pour des nationaux espagnols r\u00e9alisant des affaires \u00e0 l\u2019\u00e9tranger pour le compte d\u2019entreprises espagnoles.<\/p>\n<p style=\"text-align: justify;\">Le D\u00e9cret Royal du 330\/1999 du 26 f\u00e9vrier 1999 \u00e9tablit un certificat professionnel d\u2019activit\u00e9 d\u2019agent commercial.<\/p>\n<p style=\"text-align: justify;\">L\u2019appel \u00e0 un agent commercial repr\u00e9sente une des formules les plus \u00e9conomiques, rapides et efficaces quand il s\u2019agit de conqu\u00e9rir de nouveaux march\u00e9s, particuli\u00e8rement si les caract\u00e9ristiques et le fonctionnement du march\u00e9 choisi est inconnu.<\/p>\n<p style=\"text-align: justify;\"><strong>Marina Aranc\u00f3n &amp; Karl H. Lincke<\/strong><\/p>\n<p><a title=\"Mariscal Abogados, Avocats Madrid, Espagne\" href=\"http:\/\/www.mariscal-abogados.eu\/categoria\/investissement-et-residence-en-espagne\/\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Mariscal Abogados, Avocats francophones en Espagne<\/strong><\/a><\/p>\n<h2><strong><strong><a title=\"Eurojuris Espa\u00f1a, international network of law firms in Spain\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\" target=\"_blank\" rel=\"noopener noreferrer\"><em>Eurojuris Espa\u00f1a<\/em><\/a><\/strong><\/strong><strong><strong><a title=\"Eurojuris Espa\u00f1a, international network of law firms in Spain\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\" target=\"_blank\" rel=\"noopener noreferrer\"><em>, r\u00e9seau espagnol inernational de cabinet d\u2019avocats<\/em><\/a><\/strong><\/strong><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Faire appel aux services d\u2019un agent commercial est une formule rentable et efficace pour l\u2019entreprise quand il s\u2019agit d\u2019exporter ses biens et services ou s\u2019\u00e9tendre \u00e0 de nouveaux  march\u00e9s, aussi bien nationaux qu\u2019internationaux.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[258],"tags":[],"class_list":["post-5039","post","type-post","status-publish","format-standard","hentry","category-articles-juridiques"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Le r\u00f4le de l\u2019agent commercial<\/title>\n<meta name=\"description\" content=\"L&#039;agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Le r\u00f4le de l\u2019agent commercial\" \/>\n<meta property=\"og:description\" content=\"L&#039;agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-11T08:00:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:15:55+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Le r\u00f4le de l\u2019agent commercial en Espagne\",\"datePublished\":\"2016-04-11T08:00:39+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/\"},\"wordCount\":799,\"articleSection\":[\"Articles juridiques\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/\",\"name\":\"Le r\u00f4le de l\u2019agent commercial\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2016-04-11T08:00:39+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"L'agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/le-role-de-lagent-commercial-en-espagne\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Le r\u00f4le de l\u2019agent commercial en Espagne\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Le r\u00f4le de l\u2019agent commercial","description":"L'agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/","og_locale":"en_US","og_type":"article","og_title":"Le r\u00f4le de l\u2019agent commercial","og_description":"L'agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2016-04-11T08:00:39+00:00","article_modified_time":"2020-04-11T07:15:55+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Le r\u00f4le de l\u2019agent commercial en Espagne","datePublished":"2016-04-11T08:00:39+00:00","dateModified":"2020-04-11T07:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/"},"wordCount":799,"articleSection":["Articles juridiques"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/","name":"Le r\u00f4le de l\u2019agent commercial","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2016-04-11T08:00:39+00:00","dateModified":"2020-04-11T07:15:55+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"L'agent commercial est responsable de la promotion, n\u00e9gociation et exploitation de biens ou services au nom et pour le compte d\u2019une entreprise.","breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/le-role-de-lagent-commercial-en-espagne\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Le r\u00f4le de l\u2019agent commercial en Espagne"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5039","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5039"}],"version-history":[{"count":2,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5039\/revisions"}],"predecessor-version":[{"id":6613,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5039\/revisions\/6613"}],"wp:attachment":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}