{"id":5011,"date":"2016-04-08T08:00:19","date_gmt":"2016-04-08T08:00:19","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=5011"},"modified":"2020-04-11T07:15:55","modified_gmt":"2020-04-11T07:15:55","slug":"anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien","status":"publish","type":"post","link":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/","title":{"rendered":"\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien"},"content":{"rendered":"<p style=\"text-align: justify;\">Bisher wurde die Aufteilung des Verm\u00f6gens einer verstorbenen Person, die Erben in mehreren europ\u00e4ischen L\u00e4ndern beerben m\u00f6chte, durch das Erbrecht der entsprechenden betroffenen L\u00e4nder bestimmt.<!--more\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien--><\/p>\n<p style=\"text-align: justify;\">Im Fall von Spanien erlaubt das spanische Erbrecht jedoch die gemeinsame Anwendung von verschiedenen Rechtssystemen.<\/p>\n<p style=\"text-align: justify;\">Die Verordnung des Europ\u00e4ischen Parlaments vom 4. Juli 2012 \u00fcber die Zust\u00e4ndigkeit, das anzuwendende Recht, die Anerkennung und die Vollstreckung von Entscheidungen sowie die Annahme und Vollstreckung \u00f6ffentlicher Urkunden in Erbsachen sieht vor, dass diese Verm\u00f6gensarten einem Rechtsystem von kumulierten Rechtsvorschriften unterliegen.<\/p>\n<p style=\"text-align: justify;\">F\u00fcr die ab dem 17. August 2015 verstorbenen Personen erlaubt das <a href=\"http:\/\/www.mariscal-abogados.de\/wichtige-neuerungen-fur-auslandsdeutsche-im-internationalen-erbrecht\/\">europ\u00e4ische Erbrecht<\/a> die Verwaltung des gesamten Verm\u00f6gens in einem einzigen Verfahren; au\u00dferdem wurden die Richtlinien zur Erbfolge vereinheitlicht und schnellere und effizientere Nachfolgeregelungen gef\u00f6rdert.<\/p>\n<p style=\"text-align: justify;\">Die \u00dcbergangsbestimmungen von Artikel 83 der Verordnung sehen eine doppelte Schutzklausel f\u00fcr Erbschaftsurkunden vor, die vor dem 17. August 2015 datiert sind, in denen der Todesfall jedoch nach dem 17. August 2015 eingetreten ist. Der Artikel enth\u00e4lt eine \u00dcbergangsbestimmung zur freiwilligen Auswahl des anzuwendenden Rechtssystems. Dadurch ist es einem Franzosen, der in Spanien residiert, m\u00f6glich, die Regelung seines Nachlasses dem franz\u00f6sischen Recht anzuvertrauen, selbst wenn das franz\u00f6sische Recht diese Option gegenw\u00e4rtig noch nicht vorsieht. Die Verordnung enth\u00e4lt auch eine \u00dcbergangsbestimmung bez\u00fcglich der Bestimmungen zu den Todesursachen. Damit eine Verm\u00f6gensverf\u00fcgung durch Tod, die vor dem 17. August 2015 datiert ist, rechtskr\u00e4ftig wird, muss sie die Bedingungen, die die Verordnung an das anwendbare Recht macht, erf\u00fcllen.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Gerichtsbarkeit der spanischen Gerichte<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">In Spanien wendet der f\u00fcr das Verm\u00f6gen verantwortliche Notar nur ein Rechtssystem f\u00fcr alle Verm\u00f6genswerte an: die Vorschriften des Landes des Erblassers oder die Vorschriften des letzten europ\u00e4ischen Landes, in dem der Erblasser seinen Wohnsitz hatte. Dies spiegelt sich in der europ\u00e4ischen Verordnung wieder, mit der Neuheit, dass seit der Reform jeder EU-B\u00fcrger das Recht hat, das Rechtssystem, nach dem die Verf\u00fcgung von Todes wegen durchgef\u00fchrt werden soll, selbst auszuw\u00e4hlen.<\/p>\n<p style=\"text-align: justify;\">Gem\u00e4\u00df Artikel 21. 1) der europ\u00e4ischen Verordnung sind die spanischen Gerichte zust\u00e4ndig, \u00a0wenn der Erblasser zum Zeitpunkt des \u00a0Todes seinen Wohnsitz in Spanien hatte. In diesem Fall wird ausschlie\u00dflich spanisches Recht auf das gesamte Verm\u00f6gen angewendet.<\/p>\n<p style=\"text-align: justify;\">Artikel 21. 2) der europ\u00e4ischen Verordnung sieht ein Ausnahme vor. Hat der Erblasser seinen Hauptwohnsitz in einem anderen Land, werden die spanischen Gerichte trotzdem zust\u00e4ndig sein, wenn der Verstorbene intensive Beziehungen mit Spanien hatte. Wie genau diese intensiven Beziehungen auszusehen haben, muss aber noch n\u00e4her bestimmt werden. Dies k\u00f6nnte bedeuten, dass sich der Gro\u00dfteil der Verm\u00f6genswerte oder der Wohnsitz eines erheblichen Teils der Familie in Spanien befindet.<\/p>\n<p style=\"text-align: justify;\">Falls aus der Regel oder der Ausnahme keine eindeutige Verbindung zum spanischem Recht\u00a0 hervorgeht, haben spanische Staatsb\u00fcrger, die im EU-Ausland residieren noch eine weitere Option: sie k\u00f6nnen das anwendbare Recht selbst aussuchen. Diese Wahl muss ausdr\u00fccklich und eindeutig im Testament oder Erbvertrag formuliert sein.<\/p>\n<p style=\"text-align: justify;\">Ferner ist darauf hinzuweisen, dass die Verordnung \u00a0zum Zwecke der Effizienz und Zeitplanung vorsieht, dass Testamente und Erbvertr\u00e4ge, die in einem Mitgliedsstaat aufgesetzt werden, direkt in einem anderen gelten gemacht werden k\u00f6nnen. Mitgliedsstaaten haben gem\u00e4\u00df Artikel 41 der Verordnung die Pflicht, Gerichtsbeschl\u00fcsse anderer Mitgliedsstaaten anzuerkennen.<\/p>\n<p style=\"text-align: justify;\">Letztendlich f\u00fchrt die Verordnung mit den Artikel 62 bis 73 ein neues Mittel f\u00fcr die grenz\u00fcberschreitende Erbnachfolge ein: das europ\u00e4ische Nachlasszeugnis. Dieses Zeugnis erlaubt es den Erben, Ehegatten und anderen durch die Erbschaft Beg\u00fcnstigten, Nachweis \u00fcber ihre Eignung als Erbfolger in einem anderen Mitgliedsstaat zu erbringen um ihre Erbschaft geltend machen zu k\u00f6nnen.<\/p>\n<p style=\"text-align: justify;\"><strong>Lucie Robin &amp; Nicol\u00e1s Melchior<\/strong><\/p>\n<p><strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/a><\/strong><\/p>\n<h2><em><strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>In Spanien wendet der f\u00fcr die Verm\u00f6gensverwaltung verantwortliche Notar nach der Reform des Erbrechts f\u00fcr Ausl\u00e4nder nur ein Rechtssystem f\u00fcr alle Verm\u00f6genswerte an: die Vorschriften des Landes des Erblassers oder die Vorschriften des letzten europ\u00e4ischen Landes, in dem der Erblasser seinen Wohnsitz hatte.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-5011","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien<\/title>\n<meta name=\"description\" content=\"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien\" \/>\n<meta property=\"og:description\" content=\"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-08T08:00:19+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:15:55+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien\",\"datePublished\":\"2016-04-08T08:00:19+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/\"},\"wordCount\":621,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/\",\"name\":\"Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2016-04-08T08:00:19+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien","description":"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien","og_description":"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2016-04-08T08:00:19+00:00","article_modified_time":"2020-04-11T07:15:55+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien","datePublished":"2016-04-08T08:00:19+00:00","dateModified":"2020-04-11T07:15:55+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/"},"wordCount":621,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/","name":"Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2016-04-08T08:00:19+00:00","dateModified":"2020-04-11T07:15:55+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"Die Reform des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien erlaubt in Spanien die gemeinsame Anwendung von mehreren Rechtssystemen.","breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/anderungen-der-anwendung-des-erbrechts-fur-auslander-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"\u00c4nderungen der Anwendung des Erbrechts f\u00fcr Ausl\u00e4nder in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5011","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5011"}],"version-history":[{"count":2,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5011\/revisions"}],"predecessor-version":[{"id":6614,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5011\/revisions\/6614"}],"wp:attachment":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5011"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5011"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5011"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}