{"id":4149,"date":"2015-03-02T08:00:59","date_gmt":"2015-03-02T08:00:59","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=4149"},"modified":"2020-04-11T07:23:00","modified_gmt":"2020-04-11T07:23:00","slug":"arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien","status":"publish","type":"post","link":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/","title":{"rendered":"Arbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien"},"content":{"rendered":"<p>Bevor wir uns mit der Berechnungsweise des Dienstalters zu Entsch\u00e4digungszwecken in Spanien befassen, werden wir zun\u00e4chst erl\u00e4utern, worin der Vertrag \u00fcber Arbeitnehmer\u00fcberlassung besteht.<\/p>\n<p>Der Vertrag \u00fcber Arbeitnehmer\u00fcberlassung ist in Art. 6 des Gesetzes Nr. 14\/1994 vom 1. Juni 2014 geregelt, wodurch Leiharbeitsagenturen reguliert werden. Es handelt sich um einen Vertrag zwischen einer Leiharbeitsagentur (ETT) und einem entleihenden Unternehmen zum Zwecke des Verleihs des Arbeitnehmers durch das entleihende Unternehmen, dessen Regelungen der Arbeitnehemer unterworfen ist.<!--moreArbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien--><\/p>\n<p>Damit das entleihende Unternehmen einen solchen Vertrag mit den ETT abschlie\u03b2en kann, soll die Regelung des Art. 15 des spanischen Arbeitnehmerstatuts ber\u00fccksichtigt werden. Unter den in Art. 15 des spanischen Arbeitnehmerstatuts aufgez\u00e4hlten F\u00e4llen werden die Folgenden hervorgehoben, da sie in der Parxis am h\u00e4ifigsten vorkommen:<\/p>\n<ol>\n<li>Errichtung eines Bauwerks und\/oder Erbringung bestimmter Dienstleistungen.<\/li>\n<li>Wenn die Anforderungen des Marktes, die Anh\u00e4ufung von Aufgaben oder \u00fcbersch\u00fcssige Auftr\u00e4ge dies fordern.<\/li>\n<li>Ersatz von Arbeitnehmern, die ein Recht auf Erhalt der Arbeitsstelle haben (z.B. Mutterschafts- und Erziehungsurlaub)<\/li>\n<\/ol>\n<p>Die Vertragdauer wird in dem jeweiligen Vertrag festgesetzt.<\/p>\n<p>Dennoch erwerben Arbeitnehmer den Status eines st\u00e4ndig bei dem betreffenden Unternehmen besch\u00e4ftigten Arbeitnehmers, wenn sie w\u00e4hrend eines Zeitraums von 30 Monaten f\u00fcr eine Laufzeit von h\u00f6chstens 24 Monaten (mit oder ohne Unterbrechung) f\u00fcr die gleiche oder eine andere Arbeitsstelle im gleichen Unternehmen oder mit der gleichen Unternehemnsgruppe beauftragt waren. Die Besch\u00e4ftigung der Arbeitnehmer soll anhand zwei oder mehrerer befristeter Arbeitsvertr\u00e4ge mit gleichen oder verschiedenen befristeten Vereinbarungen erfolgen, unabh\u00e4ngig davon, ob diese dirket oder \u00fcber Leiharbeitsagenturen vermittelt wurde.<\/p>\n<p>In diesem Zusammenhang ist es wichtig, auf folgendes hinzuweisen: bez\u00fcglich der Arbeitnehmer, die zun\u00e4chst ihre Dienste zu Gunsten eines entleihenden Unternehmens anhand eines Vertrags \u00fcber Arbeitnehmer\u00fcberlassung entrichtet haben und nach Ablauf der Vertragsdauer direkt durch das entleihende Unternehmen eingestellt werden (unabh\u00e4ngig davon, ob 24 Monate abgelaufen sind), wird die Periode der Entrichtung ihrer Dienstleistungen, die von dem Vertrag \u00fcber Arbeitnehmer\u00fcberlassung vorgesehen war, zum Zwecke der Berechnung des Dienstalters sowie der Entsch\u00e4digung ber\u00fccksichtigt.<\/p>\n<p>Vor diesem Hintergrund hat das Verfassungsgericht in seiner Entscheidung vom 16. April 2012 folgendes entschieden: <em>\u201eDas Dienstalter eines Arbeitnehmers in einem bestimmten Unternehmen ist nichts anderes als die Zeitperiode, in der er ununterbrochen Dienstleistungen f\u00fcr diesen Arbeitgeber entrichtet hat, auch wenn die Entrichtung der Arbeit anhand diverser Vertr\u00e4ge verschiedener Art verrichtet wurde, einschlie\u03b2lich befristeter Vertr\u00e4ge.\u201c<\/em><\/p>\n<p>Zusammenfassend l\u00e4sst sich feststellen, dass diese Art von Vertr\u00e4gen sehr n\u00fctzlich f\u00fcr Unternehmen sind, die sich unter Ber\u00fccksichtigung der oben beschriebenen Umst\u00e4nde mit Leiharbeitsagenturen in Kontakt setzen, um freie Stellen zu besetzen oder ihr Arbeitsteam zu bestimmten Zeitpunkten zu verst\u00e4rken.<\/p>\n<p>In jedem Fall wird der Zeitraum, w\u00e4hrend dessen der Arbeitnehmer die Arbeitsleistung an das entleihende Unternehmen erbracht hat, bei der Berechnung des Dienstalters mitgerechnet und somit zum Zwecke der Entsch\u00e4digung ber\u00fccksichtigt, unter der Bedingung, dass das Arbeitnehmerstatut selbst die Berechnung der Entsch\u00e4digung bestimmt \u2013 im Falle einer gerechtfertigten oder ungerechtfertigter Entlassung. Die Dienstjahre des entlassenen Arbeitnehmers werden unabh\u00e4ngig der Art des Arbeitsvertrags ber\u00fccksichtigt.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Monika Bertram<\/strong><br \/>\n<strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/a><\/strong><\/p>\n<h2><em><strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bevor wir uns mit der Berechnungsweise des Dienstalters zu Entsch\u00e4digungszwecken in Spanien befassen, werden wir zun\u00e4chst erl\u00e4utern, worin der Vertrag \u00fcber Arbeitnehmer\u00fcberlassung besteht. Der Vertrag \u00fcber Arbeitnehmer\u00fcberlassung ist in Art. 6 des Gesetzes Nr. 14\/1994 vom 1. Juni 2014 geregelt, wodurch Leiharbeitsagenturen reguliert werden. Es handelt sich um einen Vertrag zwischen einer Leiharbeitsagentur (ETT) und [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-4149","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Leiharbeitsagenturen und Dienstalter in Spanien<\/title>\n<meta name=\"description\" content=\"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Leiharbeitsagenturen und Dienstalter in Spanien\" \/>\n<meta property=\"og:description\" content=\"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2015-03-02T08:00:59+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:23:00+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Arbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien\",\"datePublished\":\"2015-03-02T08:00:59+00:00\",\"dateModified\":\"2020-04-11T07:23:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/\"},\"wordCount\":535,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/\",\"name\":\"Leiharbeitsagenturen und Dienstalter in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2015-03-02T08:00:59+00:00\",\"dateModified\":\"2020-04-11T07:23:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Leiharbeitsagenturen und Dienstalter in Spanien","description":"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Leiharbeitsagenturen und Dienstalter in Spanien","og_description":"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2015-03-02T08:00:59+00:00","article_modified_time":"2020-04-11T07:23:00+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Arbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien","datePublished":"2015-03-02T08:00:59+00:00","dateModified":"2020-04-11T07:23:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/"},"wordCount":535,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/","name":"Leiharbeitsagenturen und Dienstalter in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2015-03-02T08:00:59+00:00","dateModified":"2020-04-11T07:23:00+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"Der Vertrag zur Arbeitnehmer\u00fcberlassung regelt die Beziehung zwischen Leiharbeitsagenturen und Unternehmen in Spanien und die Berechnung des Dienstalters.","breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/arbeitsvertrage-mit-leiharbeitsagenturen-und-die-berechnung-des-dienstalters-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Arbeitsvertr\u00e4ge mit Leiharbeitsagenturen und die Berechnung des Dienstalters in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"https:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4149","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=4149"}],"version-history":[{"count":3,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4149\/revisions"}],"predecessor-version":[{"id":6452,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4149\/revisions\/6452"}],"wp:attachment":[{"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=4149"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=4149"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=4149"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}