{"id":814,"date":"2011-01-27T08:00:28","date_gmt":"2011-01-27T08:00:28","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=814"},"modified":"2020-04-11T07:20:39","modified_gmt":"2020-04-11T07:20:39","slug":"firmengrundungen-in-spanien-und-business-etiquette","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/","title":{"rendered":"Firmengr\u00fcndungen in Spanien und Business Etiquette"},"content":{"rendered":"<p><strong>Trotz Wirtschaftskrise ist Spanien<\/strong> unver\u00e4ndert ein Land das durch angenehmes Klima, gute K\u00fcche und freundliche Menschen viele Personen anlockt. Wer nicht nur zum Urlaub bleiben m\u00f6chte und mit dem Gedanken spielt seine Selbst\u00e4ndigkeit von Deutschland nach Spanien zu verlegen, kann vor Ort <strong>relativ problemlos und kosteng\u00fcnstig ein Unternehmen gr\u00fcnden<\/strong>.<\/p>\n<p><!--more-->Die beliebteste Gesellschaftsform bei <strong>Unternehmensgr\u00fcndungen in Spanien<\/strong> ist die spanische <strong>Gesellschaft mit beschr\u00e4nkter Haftung<\/strong> (\u201eSociedad de Responsabilidad Limitada\u201c in Kurzform \u201e<strong>S.L<\/strong>.\u201c genannt). Im Folgenden werden die wesentlichen Schritte zur Gr\u00fcndung einer S.L. er\u00f6rtert:<\/p>\n<p><strong><em><span style=\"color: #000080;\">Firmenname<\/span><\/em><\/strong><\/p>\n<p>Zun\u00e4chst m\u00fcsste <strong>beim zentralen Handelsregister von Madrid<\/strong> der Gesellschaftsname f\u00fcr die neue Gesellschaft <strong>beantragt werden<\/strong>. Die Firma wird nach dem Namen stets den Zusatz \u201cS.L.\u201d f\u00fchren m\u00fcssen.<\/p>\n<p>Nach Erteilung des gew\u00fcnschten Namens durch das Zentrale Handelsregister (die Dauer liegt <strong>zwischen 4 und 7 Tage nach Antragstellung<\/strong>) ist die Gesellschaft<strong> innerhalb von zwei Monaten<\/strong> zu gr\u00fcnden.<\/p>\n<p><strong><em><span style=\"color: #000080;\">Kapital<\/span><\/em><\/strong><\/p>\n<p>Das <strong>Mindeststammkapital der S.L. betr\u00e4gt EUR 3.006,00<\/strong>. Bei der deutschen Gesellschaftsform GmbH liegt das Mindestkapital wesentlich h\u00f6her bei EUR 25.000,00. Kleinunternehmer und Existenzgr\u00fcnder wird es in Spanien somit wesentlich leichter gemacht eine solide und haftungsbegrenzte Rechtsform f\u00fcr ihre Aktivit\u00e4t w\u00e4hlen zu k\u00f6nnen.<\/p>\n<p>Im europ\u00e4ischen Vergleich d\u00fcrfte nur das Mindestkapital der britischen Gesellschaftsform der Limited unter dem einer S.L. liegen. Da es im Vereinigten K\u00f6nigreich kein gesetzlich vorgeschriebenes Mindestkapital f\u00fcr eine Limited gibt, reicht theoretisch 1 Pfund aus. Problematisch bei der Limited ist jedoch, das nachdem von deutschen Gerichten die Rechts- und Parteif\u00e4higkeit von europ\u00e4ischen Gesellschaftsformen, die in Deutschland eine Zweigniederlassung haben, anerkannt wurde, eine regelrechte Schwemme von Limiteds \u00fcber Deutschland einbrach; das Image der Limited hat darunter sehr gelitten.<\/p>\n<p><strong><em><span style=\"color: #000080;\">Gesellschafter<\/span><\/em><\/strong><\/p>\n<p>Solange die Gesellschaft <strong>mehr als einen Gesellschafter<\/strong> hat, sind diese anonym und durch Dritter auch nicht <strong>unter Einsichtnahme im Handelsregister zu identifizieren.<\/strong><\/p>\n<p><strong><em><span style=\"color: #000080;\">Sitz<\/span><\/em><\/strong><\/p>\n<p>Die spanische S.L. muss ihren Sitz<strong> innerhalb des spanischen Territoriums haben<\/strong>. Sie kann jedoch Niederlassungen in Deutschland haben. Ihre Rechts- und Parteif\u00e4higkeit wird daher von deutschen Gerichten anerkannt.<\/p>\n<p><strong><em><span style=\"color: #000080;\">Gr\u00fcndungskonto<\/span><\/em><\/strong><\/p>\n<p>Bereits <strong>vor der Gr\u00fcndung muss Urkunde ein eigens f\u00fcr das Stammkapital zu errichtendes Gr\u00fcndungskonto<\/strong> bei einer <strong>spanischen Gesch\u00e4ftsbank<\/strong> er\u00f6ffnet werden. Auf dieses Gr\u00fcndungskonto sind die Gesellschaftereinlagen einzuzahlen.<\/p>\n<p><strong><em><span style=\"color: #000080;\">Gesch\u00e4ftsf\u00fchrungsorgan<\/span><\/em><\/strong><\/p>\n<p>Das Gesch\u00e4ftsf\u00fchrungsorgan der S.L. sind die so genannten \u201c<em><strong>administradores<\/strong><\/em>\u201d bzw. \u201e<em><strong>consejeros<\/strong><\/em>\u201c (Verwalter bzw. Verwaltungsratsmitglieder). Ein weiterer Vorteil der S.L. besteht darin, dass es sich hierbei auch um nicht in Spanien ans\u00e4ssige Personen handeln kann. Sie m\u00fcssen auch <strong>keinen speziellen rechtlichen Anforderungen gen\u00fcgen<\/strong>. Das Gesch\u00e4ftsf\u00fchrungsorgan kann durch einen Alleinverwalter, zwei gemeinsam oder einzelvertretungsberechtigte Verwalter oder durch einen Verwaltungsrat ausge\u00fcbt werden.<\/p>\n<p>Es ist theoretisch m\u00f6glich, dass der Gesellschafter, der Verwalter und der Gesch\u00e4ftsf\u00fchrer ein und die selbe Person ist.<\/p>\n<p><em><strong><span style=\"color: #000080;\">Satzung<\/span><\/strong><\/em><\/p>\n<p>In der Gesellschaftssatzung sind vor allem der <strong>Sitz der Gesellschaft, das Stammkapital und seine St\u00fcckelung sowie der Gesellschaftszweck anzugeben<\/strong>. Ferner k\u00f6nnen in der Satzung vom Gesetz abweichende \u00dcbertragungsregelungen bzw. erh\u00f6hte Mehrheiten f\u00fcr die Fassung bestimmter Beschl\u00fcsse geregelt werden.<\/p>\n<p><strong><em><span style=\"color: #000080;\">Kosten\/Honorare<\/span><\/em><\/strong><\/p>\n<p>Alle Gr\u00fcndungskosten (Anwalt, Notar, Handelsregister, etc.) <strong>richten sich grunds\u00e4tzlich nach der H\u00f6he des Stammkapitals<\/strong>. Ausgehend vom Mindeststammkapital in H\u00f6he von EUR 3.006,00 w\u00fcrden sich folgende Gr\u00fcndungskosten ergeben:<\/p>\n<p>Anwaltshonorar: ca. 1.900,- \u20ac<\/p>\n<p>Notariat: ca. 350,- \u20ac<\/p>\n<p>Handelsregister: ca. 300,- \u20ac<\/p>\n<p>Gr\u00fcndungssteuer: 30,06 \u20ac (1 % des Gesellschaftskapitals)<\/p>\n<p>Namensreservierung: 25,00 \u20ac<\/p>\n<p>Nach der Gr\u00fcndung vorzunehmende Schritte<\/p>\n<p>Nach der notariellen Gr\u00fcndung w\u00e4re die <strong>Gr\u00fcndungssteuer in H\u00f6he von 1% des Stammkapitals<\/strong> einzuzahlen, eine <strong>Steueridentifikationsnummer (C.I.F.) zu beantragen<\/strong> und die <strong>Eintragung im zust\u00e4ndigen Handelsregister<\/strong> vorzunehmen.<\/p>\n<p>Vergleich GmbH und S.L.GmbH<\/p>\n<p>Gr\u00fcndungsdauer: Bis zu drei Monate<\/p>\n<p>Gesellschafter: Mindestens ein Gesellschafter<\/p>\n<p>Gesch\u00e4ftsf\u00fchrung: Mindestens ein Gesch\u00e4ftsf\u00fchrer<\/p>\n<p>Niederlassung\/Sitz: Hauptsitz Deutschland<\/p>\n<p>Nominalkapital: 25.000 Euro<\/p>\n<p>Versteuerung: K\u00f6rperschaftssteuer, Gewerbesteuer, Solidarit\u00e4tszuschlag<\/p>\n<p>IHK-Mitgliedschaft: Ja<\/p>\n<p>Gesellschafterliste einsehbar: Ja<\/p>\n<p>Pflicht zur Gewerbeanmeldung: Ja<\/p>\n<p>Doppelte Buchf\u00fchrung: Ja<\/p>\n<p>Sanktionen des Handels-\/ Gesellschaftsregisters: Zwangsgelder, zivil- und strafrechtliche Sanktionen<\/p>\n<p>S.L.<\/p>\n<p>Gr\u00fcndungsdauer: ca. zwei Monate<\/p>\n<p>Gesellschafter: Mindestens ein Gesellschafter<\/p>\n<p>Gesch\u00e4ftsf\u00fchrungNiederlassung\/Sitz: Hauptsitz Spanien<\/p>\n<p>Nominalkapital: 3.006 Euro<\/p>\n<p>Versteuerung:K\u00f6rperschaftssteuer<\/p>\n<p>IHK-Mitgliedschaft: Nein<\/p>\n<p>Gesellschafterliste einsehbar: Nein<\/p>\n<p>Pflicht zur Gewerbeanmeldung: Ja, aber i.d.R keine Steuer<\/p>\n<p>Doppelte Buchf\u00fchrung: Ja<\/p>\n<p>Sanktionen des Handels-\/ Gesellschaftsregisters: Sanktionen werden grunds\u00e4tzlich nicht verh\u00e4ngt.<\/p>\n<p>SchlussfolgerungAnhand des Vergleiches zwischen der GmbH und der S.L. kann man erkennen, dass die<strong> Vorteile bei der S.L. \u00fcberwiegen und besonders f\u00fcr geographisch ungebundene Unternehmen und Existenzgr\u00fcnder von Interesse sein d\u00fcrfte.<\/strong><\/p>\n<p>Immobilienkauf durch eine SLWer wegen der derzeit fallenden Grundst\u00fcckspreise in Spanien an den Kauf eines Ferienhauses denkt, sollte den Erwerb \u00fcber eine S.L. in Erw\u00e4gung zielen. Insbesondere im Hinblick auf einen sp\u00e4teren Verkauf bzw. Erbschaft lassen sich so zum Teil erhebliche Steuern sparen und das Immobilienverm\u00f6gen in Gesellschaftsanteile aufteilen.<\/p>\n<p>Businessetikette: Ist die Unternehmensinfrastruktur erst einmal geschaffen, sollte bei der Gesch\u00e4ftsanbahnung und den ersten Gesch\u00e4ftskontakten in Spanien Einiges beachtet werden:<\/p>\n<p>Die <strong>meisten Gesch\u00e4fte<\/strong> werden in Spanien <strong>beim Essen geschlossen<\/strong>. Gesch\u00e4ftsabschl\u00fcsse <strong>\u00fcber E-Mail sind eher die Ausnahme<\/strong>. Der spanische Gesch\u00e4ftsmann will seinen <strong>potentiellen Gesch\u00e4ftspartner pers\u00f6nlich<\/strong> kennen lernen. Daf\u00fcr bietet sich traditionell das zweist\u00fcndige Mittagessen (14:00 bis 16:00 h) an. Restaurantrechnungen werden in Spanien nicht geteilt oder gar auseinander dividiert. Es zahlt immer nur einer, selbst wenn man zu mehreren isst. Derjenige der zahlt, wird in der Regel beim n\u00e4chsten Essen eingeladen. Hierauf ist zu achten.<\/p>\n<p>Der spanische Gesch\u00e4ftsmann kleidet sich konservativer als der deutsche, auch wenn dies wie \u00fcberall auf der Welt branchenabh\u00e4ngig ist: Das Outfit eines Bankers unterscheidet sich auch in Spanien sehr von dem eines Informatikers. Trotz der hohen Temperaturen sollte man in Spanien auch im Sommer f\u00fcr Gesch\u00e4ftstermine einen diskreten Anzug bzw. ein Kost\u00fcm tragen und auf ein gepflegtes \u00c4u\u00dferes (saubere Haare, Fingern\u00e4gel und Z\u00e4hne, geputzte Schuhe und geb\u00fcgeltes Hemd) achten.<\/p>\n<p>Bei Gespr\u00e4chen sollte man nicht gleich mit der T\u00fcr ins Haus fallen und nicht auf einen Gesch\u00e4ftsabschluss dr\u00e4ngen. Es sollte zun\u00e4chst etwas Smalltalk betrieben werden. Themen die man vermeiden sollte sind Politik, j\u00fcngere spanische Geschichte und Religion. Unproblematisch sind dagegen Themen wie Sport (insbesondere Fu\u00dfball), Wetter, Investments (insbesondere Immobilie) sowie Essen und Trinken.<\/p>\n<p><strong>Karl H. Lincke<\/strong><\/p>\n<p>Mariscal Rechtsanw\u00e4lte<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Trotz Wirtschaftskrise ist Spanien unver\u00e4ndert ein Land das durch angenehmes Klima, gute K\u00fcche und freundliche Menschen viele Personen anlockt. Wer nicht nur zum Urlaub bleiben m\u00f6chte und mit dem Gedanken spielt seine Selbst\u00e4ndigkeit von Deutschland nach Spanien zu verlegen, kann vor Ort relativ problemlos und kosteng\u00fcnstig ein Unternehmen gr\u00fcnden.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[413,417,418,36,420,310,415,414,416,419],"class_list":["post-814","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen","tag-firmengrundung","tag-gmbh","tag-immobilien","tag-karl-h-lincke","tag-mariscal-abogados-rechtsanwaelte","tag-rechtsanwalt","tag-sl","tag-spanien","tag-vergleich","tag-vorteil"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Firmengr\u00fcndungen in Spanien und Business Etiquette<\/title>\n<meta name=\"description\" content=\"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Firmengr\u00fcndungen in Spanien und Business Etiquette\" \/>\n<meta property=\"og:description\" content=\"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2011-01-27T08:00:28+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:20:39+00:00\" \/>\n<meta name=\"author\" content=\"Laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/\"},\"author\":{\"name\":\"Laura\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"headline\":\"Firmengr\u00fcndungen in Spanien und Business Etiquette\",\"datePublished\":\"2011-01-27T08:00:28+00:00\",\"dateModified\":\"2020-04-11T07:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/\"},\"wordCount\":1054,\"keywords\":[\"Firmengr\u00fcndung\",\"GmbH\",\"Immobilien\",\"Karl H. Lincke\",\"Mariscal  Abogados Rechtsanwaelte\",\"Rechtsanwalt\",\"SL\",\"Spanien\",\"Vergleich\",\"Vorteil\"],\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/\",\"name\":\"Firmengr\u00fcndungen in Spanien und Business Etiquette\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2011-01-27T08:00:28+00:00\",\"dateModified\":\"2020-04-11T07:20:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"description\":\"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/firmengrundungen-in-spanien-und-business-etiquette\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Firmengr\u00fcndungen in Spanien und Business Etiquette\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"caption\":\"Laura\"},\"sameAs\":[\"http:\\\/\\\/\"],\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Firmengr\u00fcndungen in Spanien und Business Etiquette","description":"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/","og_locale":"en_US","og_type":"article","og_title":"Firmengr\u00fcndungen in Spanien und Business Etiquette","og_description":"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2011-01-27T08:00:28+00:00","article_modified_time":"2020-04-11T07:20:39+00:00","author":"Laura","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/"},"author":{"name":"Laura","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"headline":"Firmengr\u00fcndungen in Spanien und Business Etiquette","datePublished":"2011-01-27T08:00:28+00:00","dateModified":"2020-04-11T07:20:39+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/"},"wordCount":1054,"keywords":["Firmengr\u00fcndung","GmbH","Immobilien","Karl H. Lincke","Mariscal  Abogados Rechtsanwaelte","Rechtsanwalt","SL","Spanien","Vergleich","Vorteil"],"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/","name":"Firmengr\u00fcndungen in Spanien und Business Etiquette","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2011-01-27T08:00:28+00:00","dateModified":"2020-04-11T07:20:39+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"description":"Der Autor beschreibt wie man in Zeiten der Wirtschaftskrise ein Unternehmen in Spanien gr\u00fcnden kann und davon profitieren.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/firmengrundungen-in-spanien-und-business-etiquette\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Firmengr\u00fcndungen in Spanien und Business Etiquette"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed","name":"Laura","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","caption":"Laura"},"sameAs":["http:\/\/"],"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/laura\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/814","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=814"}],"version-history":[{"count":8,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/814\/revisions"}],"predecessor-version":[{"id":5670,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/814\/revisions\/5670"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=814"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=814"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=814"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}