{"id":688,"date":"2010-10-27T07:19:49","date_gmt":"2010-10-27T07:19:49","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=688"},"modified":"2020-04-11T07:20:39","modified_gmt":"2020-04-11T07:20:39","slug":"die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/","title":{"rendered":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens"},"content":{"rendered":"<p>Das noch junge <strong>spanische Insolvenzgesetz<\/strong> vertieft sich in der Vorstandshaftung von Kapitalgesellschaften. Diese <strong>neue Haftungsregelung<\/strong> erg\u00e4nzt bereits vorgesehene Regelungen sowohl bez\u00fcglich des Aktiengesellschaftsrechts als auch des Gesetzes betreffend der Gesellschaft mit beschr\u00e4nkter Haftung, und im Rahmen gesellschaftsrechtlicher Delikte des Strafgesetzbuches.<!--more--><\/p>\n<p>In der Tat widmet sich einer der Abschnitte \u00fcber das <strong>Konkursverfahren der Konkursbeurteilung<\/strong>. An dieser Stelle hat der Richter zu pr\u00fcfen, ob der Gesch\u00e4ftsf\u00fchrer oder Vorstand des Unternehmens die Insolvenzlage der Gesellschaft in irgendeiner Weise zu verschulden hat. Die Folgen eines solchen Falles stellen, wie wir sp\u00e4ter sehen werden, eine ernsthafte Bedrohung f\u00fcr Gesch\u00e4ftsf\u00fchrer dar, die ihr Amt nicht sorgf\u00e4ltig ausge\u00fcbt haben. Nachfolgend werden wir dieses Problem bez\u00fcglich der angef\u00fchrten Punkte n\u00e4her betrachten:<\/p>\n<p>\u2022 <strong>Wann eine Konkursbeurteilung erfolgt<\/strong>, die wie bereits erw\u00e4hnt dem Richter den Anlass gibt, die Verantwortlichkeit der Gesch\u00e4ftsf\u00fchrer zu hinterfragen;<\/p>\n<p>\u2022 <strong>Wer von der vorgesehenen Haftungsregelung<\/strong> im Rahmen der Insolvenzordnung betroffen ist;<\/p>\n<p>\u2022 Wann der <strong>Konkurs als schuldhaft<\/strong> herbeigef\u00fchrt einzusch\u00e4tzen ist;<\/p>\n<p>\u2022 Welche <strong>Folgen eine schuldhaft herbeigef\u00fchrte Insolvenzlage<\/strong> f\u00fcr die Gesch\u00e4ftsf\u00fchrer mit sich bringt.<\/p>\n<p>Vor der Er\u00f6rterung jeder dieser Punkte ist jedoch darauf hinzuweisen, dass es dem Richter jederzeit w\u00e4hrend des <strong>Insolvenzprozesses<\/strong> zusteht, die Beschlagnahme des Vorstandsverm\u00f6gens anzuordenen, soweit es Anhaltspunkte zu der Annahme gibt, dass <strong>der Vorstand die Insolvenzlage zu verantworten<\/strong> hat und die Verm\u00f6genswerte des bankrotten Unternehmens nicht ausreichend erscheinen, um die gesamten Schulden zu tilgen. So legt es der Artikel 48 des <strong>Insolvenzgesetzes<\/strong> fest und so haben es die Handelsgerichte bereits in zahlreichen<strong> Konkursverfahren<\/strong> angeordnet.<\/p>\n<p>In Bezugnahme auf den obig erst genannten Punkt ist an dieser Stelle klarzustellen, dass <strong>eine Konkursbeurteilung nicht in jedem Fall durchgef\u00fchrt wird<\/strong>, sondern <strong>nur<\/strong> in den folgenden Situationen: Erstens, <strong>wenn das Insolvenzverfahren zur Aufl\u00f6sung<\/strong> der betreffenden Gesellschaft f\u00fchrt, und zweitens, wenn im Verlauf des <strong>Insolvenzverfahrens eine Einigung mit den Gl\u00e4ubigern<\/strong> \u00fcber den Erlass von mehr als einem Drittel der Forderungsbetr\u00e4ge oder \u00fcber eine Verz\u00f6gerung von mehr als drei Jahren getroffen wird.<\/p>\n<p>Im Falle einer <strong>Konkursbewertung<\/strong>, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer, sondern ebenfalls:<\/p>\n<p>\u2022 Die <strong>Gesch\u00e4ftsf\u00fchrer der vergangenen zwei Jahre<\/strong>, und<\/p>\n<p>\u2022 Die sogenannten <strong>faktischen bzw. tats\u00e4chlichen Gesch\u00e4sftsf\u00fchrer<\/strong>. Hierbei handelt es sich um Personen, die zwar nicht formell zum Vorstandsmitglied ernannt wurden und damit nicht als solche im Handelsregister eingetragen sind, die die Gesellschaft jedoch in der Praxis eigentlich geleitet und verwaltet haben. Erfahrungsgem\u00e4\u03b2 ist diese Situation in ausl\u00e4ndischen Tochtergesellschaften gel\u00e4ufig, in denen der ernannte Gesch\u00e4ftsf\u00fchrer auf Anweisung des Vorstands der Muttergesellschaft handelt. Daher kann das Gericht eine Beurteilung der Verantwortlichkeit dieser F\u00fchrungskr\u00e4fte oder faktischen Gesch\u00e4ftsf\u00fchrer vornehmen und sie, wie wir sp\u00e4ter sehen werden, verurteilen.<\/p>\n<p>Im Rahmen des Beurteilungsstadiums kann das Gericht den <strong>Konkurs der Gesellschaft als zuf\u00e4llig oder verschuldet einstufen<\/strong>. Nur im letzteren Fall haftet der Vorstand. Der Konkurs gilt als schuldhaft verursacht und f\u00fchrt mithin in folgenden F\u00e4llen zu einer Haftung des Vorstands:<\/p>\n<p>\u2022 Wenn eine Gesellschaft die <strong>Verpflichtung der ordnungsgem\u00e4\u03b2en Buchhaltung wesentlich missachtet<\/strong> oder Unregelm\u00e4\u03b2igkeiten in ihrer F\u00fchrung auftreten,<\/p>\n<p>\u2022 Wenn die im <strong>Insolvenzverfahren von der Gesellschaft<\/strong> vorgelegten Unterlagen schwerwiegende Ungenauigkeiten enthalten,<\/p>\n<p>\u2022 Wenn eine Gesellschaft einen Teil oder ihr gesamtes <strong>Verm\u00f6gen geheim h\u00e4lt<\/strong> oder sich dessen zu Lasten ihrer Gl\u00e4ubiger entledigt,<\/p>\n<p>\u2022 Wenn eine Gesellschaft Handlungen in der Absicht vorgenommen hat, eine scheinbare<strong> Verm\u00f6genssituation vorzut\u00e4uschen<\/strong>.<\/p>\n<p>In den folgenden Situationen legt das <strong>Insolvenzgesetz die Vermutung des Konkursverschuldens<\/strong> fest, mit der M\u00f6glichkeit eines Gegenbeweises:<\/p>\n<p>\u2022 Wenn die Pflicht die<strong> Insolvenz der Gesellschaft<\/strong> anzumelden missachtet wurde,<\/p>\n<p>\u2022 Wenn die Gesellschaft ihren Mitwirkungspflichten betreffend dem Richter und der <strong>Konkursverwaltung<\/strong> nicht nachkommt,<\/p>\n<p>\u2022 Wenn die Gesellschaft keine Jahresrechnungen erstellt hat, diese keiner Wirtschaftspr\u00fcfungsgesellschaft vorgelegt wurden, oder wenn die genehmigten Rechnungen in einem der letzten drei Rechnungsjahre nicht im Handelsregister hinterlegt wurden. Diese Schuldvermutung verdeutlicht die Gewichtigkeit der Hinterlegung der Jahresrechnungen im Handelsregister, eine Verpflichtung, die wiederholt von Gesellschaften mit der Absicht verletzt wird, ihre finanziellen Ergebnisse nicht zu offenbaren.<\/p>\n<p>Die Beurteilungsabteilung kann mittels eines Urteils das Verfahren beenden, indem sie entsprechend den vorhergehenden Erl\u00e4uterungen die <strong>Insolvenzlage als zuf\u00e4llig oder schuldhaft<\/strong> herbeigef\u00fchrt bekundet. Eine durch den Vorstand verschuldete<strong> Konkurssituation<\/strong> kann ernste Folgen nach sich ziehen, da das Gericht die Gesch\u00e4ftsf\u00fchrer dazu verurteilen kann, den Konkursgl\u00e4ubigern die ihnen jeweilig zustehenden Geldbetr\u00e4ge zu zahlen, welche nicht \u00fcber die Liquidierung der Gesellschaft bezogen werden k\u00f6nnen. Zudem kann das Gericht den Vorstand f\u00fcr unf\u00e4hig erkl\u00e4ren, Gesch\u00e4ftsf\u00fchrungs- oder Vertretungsaufgaben mit einer Frist von zwei bis f\u00fcnfzehn Jahren wahrzunehmen. Desweitern k\u00f6nnen dem Vorstand jegliche Rechte, welche er gegen\u00fcber der insolventen Gesellschaft hatte, abgesprochen werden, um das auf diese Weise erworbene Verm\u00f6gen zur\u00fcckzuerstatten und so den Schaden zu kompensieren.<\/p>\n<p>Aus diesen Gr\u00fcnden ist es ratsam, dass sich <strong>Gesch\u00e4ftsf\u00fchrer bei der allt\u00e4glichen Arbeit kompetente Rechts- und Finanzberatung<\/strong> einholen, um so die gravierenden Folgen, die eine Missachtung ihrer unternehmerischen und administrativen Pflichten bewirken kann, zu vermeiden.<\/p>\n<p><span style=\"color: #000000;\"><strong>Mariano Jim\u00e9nez<br \/>\n<\/strong><\/span><a href=\"mailto:mjimenez@mariscal-abogados.com\">mjimenez@mariscal-abogados.com<\/a><br \/>\n<span style=\"color: #07076c;\"><a title=\"Mariscal &amp; Asociados, Abogados\" href=\"http:\/\/www.mariscal-abogados.com\/de\/veroffentlichungen\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal &amp; Asociados, Abogados<\/a><\/span><br \/>\n<strong><span style=\"color: #000080;\"><a title=\"Mitglieder von Eurojuris Espa\u00f1a\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/quienes-somos\/despachos-asociados\/\" target=\"_self\" rel=\"noopener noreferrer\"><span style=\"color: #07076c;\">Mitglieder von Eurojuris Espa\u00f1a<\/span><\/a><\/span><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das noch junge spanische Insolvenzgesetz vertieft sich in der Vorstandshaftung von Kapitalgesellschaften. Diese neue Haftungsregelung erg\u00e4nzt bereits vorgesehene Regelungen sowohl bez\u00fcglich des Aktiengesellschaftsrechts als auch des Gesetzes betreffend der Gesellschaft mit beschr\u00e4nkter Haftung, und im Rahmen gesellschaftsrechtlicher Delikte des Strafgesetzbuches.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[7,454,453,284,285,286,455],"class_list":["post-688","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen","tag-eurojuris-espana","tag-haftungsregelung-spanien","tag-insolvenzgesetz-spanien","tag-insolvenzprozess-spanien","tag-insolvenzverfahren-spanien","tag-konkursverfahren-spanien","tag-mariscal-abogados-abogados-rechtsanwaelte-spanien"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Vorstandshaftung im Rahmen des Insolvenzverfahrens<\/title>\n<meta name=\"description\" content=\"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens\" \/>\n<meta property=\"og:description\" content=\"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2010-10-27T07:19:49+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:20:39+00:00\" \/>\n<meta name=\"author\" content=\"Laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/\"},\"author\":{\"name\":\"Laura\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"headline\":\"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens\",\"datePublished\":\"2010-10-27T07:19:49+00:00\",\"dateModified\":\"2020-04-11T07:20:39+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/\"},\"wordCount\":865,\"keywords\":[\"Eurojuris Espa\u00f1a\",\"haftungsregelung spanien\",\"insolvenzgesetz spanien\",\"insolvenzprozess spanien\",\"Insolvenzverfahren Spanien\",\"konkursverfahren spanien\",\"Mariscal Abogados abogados rechtsanwaelte spanien\"],\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/\",\"name\":\"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2010-10-27T07:19:49+00:00\",\"dateModified\":\"2020-04-11T07:20:39+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"description\":\"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"caption\":\"Laura\"},\"sameAs\":[\"http:\\\/\\\/\"],\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens","description":"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/","og_locale":"en_US","og_type":"article","og_title":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens","og_description":"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2010-10-27T07:19:49+00:00","article_modified_time":"2020-04-11T07:20:39+00:00","author":"Laura","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/"},"author":{"name":"Laura","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"headline":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens","datePublished":"2010-10-27T07:19:49+00:00","dateModified":"2020-04-11T07:20:39+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/"},"wordCount":865,"keywords":["Eurojuris Espa\u00f1a","haftungsregelung spanien","insolvenzgesetz spanien","insolvenzprozess spanien","Insolvenzverfahren Spanien","konkursverfahren spanien","Mariscal Abogados abogados rechtsanwaelte spanien"],"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/","name":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2010-10-27T07:19:49+00:00","dateModified":"2020-04-11T07:20:39+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"description":"Im Falle einer Konkursbewertung in Spanien, betrifft die Bedrohung einer m\u00f6glichen Haftung nicht nur die gegenw\u00e4rtigen Gesch\u00e4ftsf\u00fchrer. In diesem Artikel betrachtet man dieses Problem.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/die-vorstandshaftung-im-rahmen-des-insolvenzverfahrens\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Die Vorstandshaftung im Rahmen des Insolvenzverfahrens"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed","name":"Laura","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","caption":"Laura"},"sameAs":["http:\/\/"],"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/laura\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/688","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=688"}],"version-history":[{"count":9,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/688\/revisions"}],"predecessor-version":[{"id":6363,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/688\/revisions\/6363"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=688"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=688"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=688"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}