{"id":5581,"date":"2016-08-29T08:00:25","date_gmt":"2016-08-29T08:00:25","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=5581"},"modified":"2020-04-11T07:15:30","modified_gmt":"2020-04-11T07:15:30","slug":"patentierbarkeit-erfindungen-spanien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/patentierbarkeit-erfindungen-spanien\/","title":{"rendered":"Die Patentierbarkeit von Erfindungen in Spanien"},"content":{"rendered":"<p style=\"text-align: justify;\">Bestimmte Dinge k\u00f6nnen nicht als Erfindung definiert werden und sind daher auch nicht patentierf\u00e4hig. Hierzu z\u00e4hlen beispielsweise Entdeckungen, wissenschaftliche Theorien, mathematische Methoden, literarische und k\u00fcnstlerische Werke und \u00e4sthetische Sch\u00f6pfungen ebenso wie wissenschaftliche Werke, Spielregeln und Spielmethoden f\u00fcr intellektuelle und wirtschaftliche Aktivit\u00e4ten, Computerprogramme \u2013 auch wenn es Erfindungen im Softwarebereich gibt, die sich patentieren lassen \u2013 und die Art der Pr\u00e4sentation von Informationen.<!--more--><\/p>\n<p style=\"text-align: justify;\">Drei Voraussetzungen m\u00fcssen erf\u00fcllt werden, damit Erfindungen patentierf\u00e4hig sind:<\/p>\n<h2 style=\"text-align: justify;\">Die Erfindung ist neu<\/h2>\n<p style=\"text-align: justify;\">Eine Erfindung gilt als neu, wenn sie vor Patentanmeldung der \u00d6ffentlichkeit weder in Spanien noch im Ausland weder durch schriftliche und m\u00fcndliche Verbreitung noch durch ihre Verwendung zug\u00e4nglich war.<\/p>\n<p style=\"text-align: justify;\">Es spielt dabei keine Rolle, ob die Verbreitung durch den Antragsteller selbst erfolgt ist oder ob die Erfindung in der \u00d6ffentlichkeit keine grosse Wahrnehmung hatte. War die Erfindung der \u00d6ffentlichkeit auf irgendeine Art und Weise zug\u00e4nglich, ist sie nicht mehr patentierf\u00e4hig. Das m\u00f6gliche Patent wird entweder abgelehnt oder als ung\u00fcltig erkl\u00e4rt.<\/p>\n<h2 style=\"text-align: justify;\">Die erfinderische T\u00e4tigkeit<\/h2>\n<p style=\"text-align: justify;\">Die Erfindung darf f\u00fcr einen Experten der Materie nicht sofort erkennbar sein. Dabei muss der Stand der Technik in Betracht gezogen werden: dass heisst, all das, was vor der Anmeldung des Patents weltweit bereits \u00fcber die Materie bekannt war und verbreitet wurde. Auch wenn eine Erfindung neu ist, kann diese nicht unbedingt patentiert werden, solange die erfinderische T\u00e4tigkeit offensichtlich ist.<\/p>\n<h2 style=\"text-align: justify;\">Die gewerbliche Anwendbarkeit<\/h2>\n<p style=\"text-align: justify;\">Dieser Aspekt wird sehr umfassend verstanden. Dass heisst, eine Erfindung findet gewerbliche Anwendung, wenn sie in der Industrie, einschliesslich des landwirtschaftlichen Sektors, hergestellt und verwendet werden kann. Kraft Gesetz gibt es bestimmte Bereiche, deren gewerbliche \u00a0Anwendbarkeit nicht Voraussetzung ist: dazu geh\u00f6ren die Methoden der Diagnostik und chirurgische oder therapeutische Behandlungen des menschlichen oder tierischen Organismus; Instrumente oder Apparate, die in diesen Behandlungen verwendet werden, haben eine gewerbliche Anwendbarkeit vorzuweisen.<\/p>\n<p style=\"text-align: justify;\">Erfindungen k\u00f6nnen sowohl auf Produkten wie auch auf Verfahrensweisen (einschliesslich deren Verwendungen) beruhen.<\/p>\n<h3 style=\"text-align: justify;\">Alexander Zuazo<\/h3>\n<hr \/>\n<p style=\"text-align: justify;\"><strong><span class=\"cursiva-azul\">Weitere Artikel zum Thema<\/span>:<\/strong><\/p>\n<p style=\"text-align: justify;\"><em>Das spanische Patenterteilungsverfahren<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Patenterteilung versus Gebrauchsmuster<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Anmeldung eines europ\u00e4ischen Patents beim Europ\u00e4ischen Patentamt<\/em><\/p>\n<p style=\"text-align: justify;\"><em>Mehrfacher Patentschutz durch das Europ\u00e4ische Patent und das PCT-Patent<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Erfindungen m\u00fcssen drei wesentliche Voraussetzungen erf\u00fcllen, damit sie zu einem Patent angemeldet werden k\u00f6nnen: die Erfindung muss neu sein, d.h. sie war der \u00d6ffentlichkeit vorher nicht zug\u00e4nglich; die erfinderische T\u00e4tigkeit darf f\u00fcr Fachleute nicht evident sein und die Erfindung muss eine gewerblich Anwendbarkeit vorweisen. Sowohl Produkte als auch Prozesse k\u00f6nnen zu einem Patent angemeldet werden.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-5581","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien<\/title>\n<meta name=\"description\" content=\"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien\" \/>\n<meta property=\"og:description\" content=\"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-08-29T08:00:25+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:15:30+00:00\" \/>\n<meta name=\"author\" content=\"Mariscal &amp; Abogados Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@MariscalLawyers\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariscal &amp; Abogados Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/patentierbarkeit-erfindungen-spanien\\\/\"},\"author\":{\"name\":\"Mariscal &amp; Abogados Abogados\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/506dd6715b030c84307e7258b2a91f54\"},\"headline\":\"Die Patentierbarkeit von Erfindungen in Spanien\",\"datePublished\":\"2016-08-29T08:00:25+00:00\",\"dateModified\":\"2020-04-11T07:15:30+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/patentierbarkeit-erfindungen-spanien\\\/\"},\"wordCount\":361,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/patentierbarkeit-erfindungen-spanien\\\/\",\"url\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\\\/\",\"name\":\"Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2016-08-29T08:00:25+00:00\",\"dateModified\":\"2020-04-11T07:15:30+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/506dd6715b030c84307e7258b2a91f54\"},\"description\":\"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.mariscal-abogados.de\\\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Patentierbarkeit von Erfindungen in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/506dd6715b030c84307e7258b2a91f54\",\"name\":\"Mariscal &amp; Abogados Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g\",\"caption\":\"Mariscal &amp; Abogados Abogados\"},\"description\":\"Mariscal &amp; Abogados is an international law firm with a multidisciplinary approach based in the capital centre of Spain, Madrid.\",\"sameAs\":[\"http:\\\/\\\/www.mariscal-abogados.com\\\/\",\"https:\\\/\\\/x.com\\\/MariscalLawyers\"],\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/mariscalabogados\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien","description":"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien","og_description":"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.","og_url":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2016-08-29T08:00:25+00:00","article_modified_time":"2020-04-11T07:15:30+00:00","author":"Mariscal &amp; Abogados Abogados","twitter_card":"summary_large_image","twitter_creator":"@MariscalLawyers","twitter_misc":{"Written by":"Mariscal &amp; Abogados Abogados","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/patentierbarkeit-erfindungen-spanien\/"},"author":{"name":"Mariscal &amp; Abogados Abogados","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/506dd6715b030c84307e7258b2a91f54"},"headline":"Die Patentierbarkeit von Erfindungen in Spanien","datePublished":"2016-08-29T08:00:25+00:00","dateModified":"2020-04-11T07:15:30+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/patentierbarkeit-erfindungen-spanien\/"},"wordCount":361,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/patentierbarkeit-erfindungen-spanien\/","url":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/","name":"Die Patentierbarkeit von Erfindungen | Rechtsberatung Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2016-08-29T08:00:25+00:00","dateModified":"2020-04-11T07:15:30+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/506dd6715b030c84307e7258b2a91f54"},"description":"Voraussetzungen der Patentierbarkeit: die Erfindung ist neu, hat eine erkennbare erfinderische T\u00e4tigkeit sowie gewerbliche Anwendbarkeit.","breadcrumb":{"@id":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.mariscal-abogados.de\/voraussetzungen-zur-patentierbarkeit-von-erfindungen-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Die Patentierbarkeit von Erfindungen in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/506dd6715b030c84307e7258b2a91f54","name":"Mariscal &amp; Abogados Abogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/aea774a02f9122b721c98700235bf3ad9c2be33c91a5b57bbc7c4ec69282d853?s=96&d=blank&r=g","caption":"Mariscal &amp; Abogados Abogados"},"description":"Mariscal &amp; Abogados is an international law firm with a multidisciplinary approach based in the capital centre of Spain, Madrid.","sameAs":["http:\/\/www.mariscal-abogados.com\/","https:\/\/x.com\/MariscalLawyers"],"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/mariscalabogados\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5581","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5581"}],"version-history":[{"count":2,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5581\/revisions"}],"predecessor-version":[{"id":5765,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5581\/revisions\/5765"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5581"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5581"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5581"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}