{"id":5148,"date":"2016-05-11T08:00:36","date_gmt":"2016-05-11T08:00:36","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=5148"},"modified":"2020-04-11T07:15:54","modified_gmt":"2020-04-11T07:15:54","slug":"masnahmen-zur-geldwaschepravention-in-spanien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/","title":{"rendered":"Ma\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien"},"content":{"rendered":"<p style=\"text-align: justify;\">Geldw\u00e4sche ist definiert als das verdeckte Einschleusen illegal erworbener Verm\u00f6genswerte, die den Anschein der Rechtm\u00e4ssigkeit oder Legalit\u00e4t haben, in den legalen Wirtschaftskreislauf.<!--moreMa\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien--><\/p>\n<p style=\"text-align: justify;\">Auf internationaler Ebene ist daf\u00fcr die <span class=\"cursiva-azul\">Financial Action Task Force (on Money Laundering)\u00a0(FATF, \u00a0die Arbeitsgruppe f\u00fcr finanzielle Ma\u00dfnahmen (gegen Geldw\u00e4sche)<\/span>, die 1989 vom G-7 Gipfel als international f\u00fchrendes Gremium zur Bek\u00e4mpfung der Geldw\u00e4sche gegr\u00fcndet wurde, verantwortlich.<\/p>\n<p style=\"text-align: justify;\">In Spanien ist die <span class=\"cursiva-azul\">Comisi\u00f3n de Blanqueo de Capitales e Infracciones Monetarias<\/span> (<span class=\"cursiva-azul\">Kommision f\u00fcr Geldw\u00e4sche und Geldverst\u00f6sse<\/span>) die verantwortliche Institution f\u00fcr die Entwicklung einer pr\u00e4ventiven Politik im Kampf gegen Geldw\u00e4sche.<\/p>\n<p style=\"text-align: justify;\">Mit der Bewilligung des k\u00f6niglichen Dekrets 304\/2014 im Mai 2014 bleibt die Verordnung des Gesetzes 10\/2010 vom 28. April zur <a href=\"http:\/\/www.mariscal-abogados.de\/datenschutz-in-der-gesetzgebung-zur-geldwaeschepraevention-in-spanien\/\">Bek\u00e4mpfung von Geldw\u00e4sche und Terrorismusfinanzierung in Spanien<\/a> bestehen.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Zur Geldw\u00e4schepr\u00e4vention verpflichtete Personengruppen<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Diese gesetzliche Regelung setzt fest, welche Personen und Institutionen zur Geldw\u00e4schepr\u00e4vention verpflichtet sind und dem Gesetz zur Pr\u00e4vention von Geldw\u00e4sche nach gem\u00e4ss zu handeln haben; hierzu geh\u00f6ren:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Kreditinstitute<\/li>\n<li>Wertpapierfirmen<\/li>\n<li>Beteiligungsgesellschaften von Risikokapital<\/li>\n<li>Wirtschaftspr\u00fcfer, externe Buchhalter und Steuerberater<\/li>\n<li>Immobilientr\u00e4gerschaften und diejenigen, die professionell der Agentur- und Vermittlungst\u00e4tigkeit im Immobilienkauf nachgehen<\/li>\n<li>Notare und Grundbuchf\u00fchrer<\/li>\n<li>Anw\u00e4lte, Rechtspr\u00fcfer und andere\u00a0 Selbst\u00e4ndige, \u00a0wenn diese im Namen ihrer Kunden Beratungst\u00e4tigkeiten im Zusammenhang mit dem Kauf- und Verkauf von Immobilien vornehmen<\/li>\n<li>Spielcasinos<\/li>\n<li>Personen, die beruflich mit Schmuck, Edelsteinen oder Edelmetallen handeln<\/li>\n<li>Personen, die beruflich mit Kunstgegenst\u00e4nden oder Antiquit\u00e4ten handeln<\/li>\n<\/ul>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Verpflichtungen nach der gesetzlichen Regelung zur Geldw\u00e4schepr\u00e4vention<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Die verpflichteten Personen m\u00fcssen beweiskr\u00e4ftige Kopien der offiziellen Identifikationsdokumente auf den entsprechenden optischen, magnetischen oder elektronischen Datentr\u00e4gern aufbewahren.<\/p>\n<p style=\"text-align: justify;\">Ebenso m\u00fcssen auf denselben Datentr\u00e4gern Kopien gespeichert werden, die die Durchf\u00fchrung von Einzahlungen, Entnahmen oder Transaktionen von Mittel aus dem Konto eines Kreditinstitutes beweisen; des weiteren werden Kopien, die die Beauftragung oder den Erhalt von \u00dcberweisungen von Mitteln, die \u00fcber Zahlungsinstitute erfolgt sind sowie Nachweise \u00fcber Geldwechselgesch\u00e4fte gespeichert.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Von der Geldw\u00e4schepr\u00e4vention ausgenommene Personengruppen<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Von diesen Massnahmen ausgenommen sind diejenigen generell zur Geldw\u00e4schepr\u00e4vention verpflichteten Personengruppen, die weniger als 10 Angestellte haben und deren Jahresumsatz bzw. Jahresbilanz \u00a02 Millionen Euro nicht \u00fcberschreitet. In diesen F\u00e4llen k\u00f6nnen Papierkopien der Identifikationsdokumente aufbewahrt werden. Die verpflichteten Personen, die Teil einer \u00a0Unternehmensgruppe sind, die die erw\u00e4hnten Angaben \u00fcberschreitet, k\u00f6nnen diese Ausnahme nicht f\u00fcr sich beanspruchen.<\/p>\n<p style=\"text-align: justify;\">Die durch Artikel 2.1 i) bis u) zur Geldw\u00e4schepr\u00e4vention verpflichteten Personen, die weniger als 10 Arbeitskr\u00e4fte haben und deren Jahresumsatz bzw. Jahresbilanz die 2 Mio. Euro Grenze nicht \u00fcberschreitet, sind von den folgenden Pr\u00e4ventionsmassnahmen ausgeschlossen:<\/p>\n<ul style=\"text-align: justify;\">\n<li>von der Dokumentation einer Risikoanalyse<\/li>\n<li>von der Erstellung eines Handbuchs mit Pr\u00e4ventionsmassnahmen<\/li>\n<li>es m\u00fcssen keine interne Kontrollorgane etabliert werden<\/li>\n<li>eine externen Kontrolle ist nicht erforderlich<\/li>\n<li>es muss kein Ausbildungsplan f\u00fcr die Belegschaft geschaffen werden.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Im Allgemeinen flexibilisiert man die Anforderungen f\u00fcr die Verpflichteten mit kleineren Unternehmen, dies bedeutet weder, weniger Kontrolle zu haben noch die Pflicht nicht wahrzunehmen, in entdeckten Verdachtsf\u00e4llen die entsprechenden Beh\u00f6rden dar\u00fcber zu informieren.<\/p>\n<p style=\"text-align: justify;\"><strong>Laura Chetail &amp; Nicol\u00e1s Melchior<\/strong><br \/>\n<strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/a><\/strong><br \/>\n<strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Die gesetzliche Regelung 10\/2010 zur Bek\u00e4mpfung von Geldw\u00e4sche und Terrorismusfinanzierung in Spanien bestimmt die Personengruppen, die bestimmten Verpflichtungen unterliegen. Hierzu z\u00e4hlen beispielsweise Kreditinstitute, Beteiligungsgesellschaften, Wirtschaftspr\u00fcfer, Anw\u00e4lte oder Immobilienh\u00e4ndler. Ausgeschlossen sind Unternehmen mit weniger als 10 Mitarbeitern und einem Jahresumsatz von unter 2 Mio. Euro. <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-5148","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Geldw\u00e4schepr\u00e4vention in Spanien<\/title>\n<meta name=\"description\" content=\"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\/2010 geregelt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Geldw\u00e4schepr\u00e4vention in Spanien\" \/>\n<meta property=\"og:description\" content=\"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\/2010 geregelt.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-05-11T08:00:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:15:54+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Ma\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien\",\"datePublished\":\"2016-05-11T08:00:36+00:00\",\"dateModified\":\"2020-04-11T07:15:54+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/\"},\"wordCount\":538,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/\",\"name\":\"Geldw\u00e4schepr\u00e4vention in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2016-05-11T08:00:36+00:00\",\"dateModified\":\"2020-04-11T07:15:54+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\\\/2010 geregelt.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/masnahmen-zur-geldwaschepravention-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Ma\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Geldw\u00e4schepr\u00e4vention in Spanien","description":"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\/2010 geregelt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Geldw\u00e4schepr\u00e4vention in Spanien","og_description":"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\/2010 geregelt.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2016-05-11T08:00:36+00:00","article_modified_time":"2020-04-11T07:15:54+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Ma\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien","datePublished":"2016-05-11T08:00:36+00:00","dateModified":"2020-04-11T07:15:54+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/"},"wordCount":538,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/","name":"Geldw\u00e4schepr\u00e4vention in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2016-05-11T08:00:36+00:00","dateModified":"2020-04-11T07:15:54+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"Die Ma\u00dfnahmen und Personengruppen zur Pr\u00e4vention von Geldw\u00e4sche und Terrorismus in Spanien sind im Gesetz 10\/2010 geregelt.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/masnahmen-zur-geldwaschepravention-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Ma\u00dfnahmen zur Geldw\u00e4schepr\u00e4vention in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5148","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5148"}],"version-history":[{"count":2,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5148\/revisions"}],"predecessor-version":[{"id":6604,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5148\/revisions\/6604"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5148"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5148"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5148"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}