{"id":5007,"date":"2016-04-19T08:00:07","date_gmt":"2016-04-19T08:00:07","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=5007"},"modified":"2020-04-11T07:15:55","modified_gmt":"2020-04-11T07:15:55","slug":"regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/","title":{"rendered":"Regelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer"},"content":{"rendered":"<p style=\"text-align: justify;\">Im Fall von Copland v. the United Kingdom vom 3. April 2007 hat der Europ\u00e4ische Gerichtshof beschlossen, dass der Begriff <span class=\"cursiva-azul\">Privatleben<\/span> und<span class=\"cursiva-azul\">Kommunikation<\/span> innerhalb des Bedeutungsbereichs von Artikel 8.1 der Europ\u00e4ischen Menschenrechtskonvention sowohl f\u00fcr Emails als auch f\u00fcr Telefonanrufe, die von Gesch\u00e4ftsr\u00e4umen aus get\u00e4tigt werden, gilt.<!--moreRegelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer --><\/p>\n<p style=\"text-align: justify;\">Die europ\u00e4ischen Richter entschieden, dass ein Arbeitnehmer einen rechtm\u00e4\u00dfigen guten Glauben in die Privatsph\u00e4re seiner Anrufe, Mitteilungen und Emails haben darf, wenn der Arbeitnehmer nicht \u00fcber den Zugang des Arbeitgebers zur Kommunikation des Arbeitnehmers und das Risiko der<a href=\"http:\/\/www.mariscal-abogados.de\/kontrollen-durch-die-gewerbeaufsicht-in-spanien\/\">\u00dcberwachung und Kontrolle<\/a> informiert ist.<\/p>\n<p style=\"text-align: justify;\">Die spanischen Richter wenden den Beschluss von Copland v. the United Kingdom strikt an und vertrauen auf den guten Glauben der Arbeitnehmer und auf deren entsprechend angebrachten und rechtm\u00e4\u00dfigen Erwartungen in Bezug auf die Privatsph\u00e4re ihrer Kommunikation.<\/p>\n<p style=\"text-align: justify;\">Die Urteilsfindung des Obersten Gerichtshofs vom 26. September 2007 beruht auf Artikel 20.3 des Arbeitnehmerstatuts, das die Arbeitgeber mit einer \u00dcberwachungs- und Kontrollfunktion ausstattet, und auf der Anforderung an den guten Glaubens in der Arbeitsbeziehung.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Bedingungen an die Kontrolle der Arbeitnehmerkommunikation<\/strong><\/span><\/h2>\n<p style=\"text-align: justify;\">Durch das Urteil wurde beschlossen, dass die \u00dcberwachung der Kommunikation der Arbeitnehmer folgende Bedingungen erf\u00fcllen muss, um rechtm\u00e4\u00dfig zu sein:<\/p>\n<ul style=\"text-align: justify;\">\n<li>Das Unternehmen muss den Arbeitnehmer \u00fcber die bestehenden Regulierungen dar\u00fcber, wie private Kommunikation von Angestellten gehandhabt wird, im Voraus informieren.<\/li>\n<li>Der Arbeitgeber muss den Arbeitnehmer \u00fcber die M\u00f6glichkeit der Kontrolle und \u00dcberwachung im Voraus informieren.<\/li>\n<\/ul>\n<p style=\"text-align: justify;\">Die Anwendung dieser Rechtssprechung kann im Urteil des Obersten Gerichtshofs vom 7. Dezember 2011 nachvollzogen werden. Die Richter erkl\u00e4ren, dass f\u00fcr die Arbeitnehmer ein absolutes Verbot bestand, die ihnen zur Verf\u00fcgung gestellten Computer f\u00fcr den Zweck der privaten Kommunikation zu verwenden.<\/p>\n<p style=\"text-align: justify;\">Dieses uneingeschr\u00e4nkte Verbot ist rechtm\u00e4\u00dfig. Daher konnte der Arbeitnehmer von keinerlei Vertraulichkeit bez\u00fcglich der \u00fcber diesen Computer durchgef\u00fchrten privaten Kommunikation ausgehen. \u00dcberdies hatte der Arbeitgeber die Arbeitnehmer zus\u00e4tzlich \u00fcber die M\u00f6glichkeit der Kontrolle dieser Computer informiert. Daher hatte der Arbeitgeber das Recht, die von diesen Ger\u00e4ten aus versandten und erhaltenen Emails zur Kontrolle einzusehen.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Kommunikation durch SMS<\/strong><\/span><\/h2>\n<p style=\"text-align: justify;\">Die Streitfrage, ob der Arbeitgeber Nachrichten kontrollieren darf, die der Arbeitnehmer von seinem Gesch\u00e4ftstelefon aus versendet oder darauf empf\u00e4ngt, ist umso relevanter, da von den franz\u00f6sischen Gerichte j\u00fcngst dar\u00fcber ein Urteil gef\u00e4llt wurde.<\/p>\n<p style=\"text-align: justify;\">In einem Urteil vom 10. Februar 2015 hat der franz\u00f6sische Oberste Gerichtshof den Grundsatz festgelegt, dass alle von einem Gesch\u00e4ftstelefon aus versendeten oder empfangen Mitteilungen einen gesch\u00e4ftlichen Zusammenhang haben sollten. Diese Annahme hat dazu gef\u00fchrt, dass der Gerichtshof dem Arbeitgeber zugesteht, <span class=\"cursiva-azul\">(1)<\/span> die Nachrichten, die ein Arbeitnehmer empfangen oder versendet hat, \u00a0zu durchsuchen und <span class=\"cursiva-azul\">(2)<\/span> diese Nachrichten als rechtm\u00e4\u00dfige Beweismittel w\u00e4hrend eines Verfahrens zuzulassen.<\/p>\n<h2 style=\"text-align: justify;\"><span style=\"color: #000080;\"><strong>Die Rechtm\u00e4\u00dfigkeit der \u00dcberwachung von SMS und Emails in Spanien<\/strong><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p style=\"text-align: justify;\">Im spanischen Gesetz gibt es diesbez\u00fcglich keine eindeutige Stellungnahme. Dennoch bietet die Urteilsfindung des Verfassungsgerichts vom 7. Oktober 2013 eine konstruktive Antwort, indem einem Urteil vom 27. April 2010 des Obersten Gerichtshofs von Madrid zugestimmt wird. In diesem Urteil wurde eine Textnachricht, die von einem Arbeitnehmer versandt wurde, als Beweismittel ausgeschlossen. Im Verfahren hatte das Unternehmen sowohl den Computer als auch das Mobiltelefon als Beweismittel zur Verf\u00fcgung gestellt, jedoch sind im betroffenen Sektor nur die Emails als rechtsg\u00fcltiges Beweismittel im Tarifvertrag aufgef\u00fchrt.<\/p>\n<p style=\"text-align: justify;\">Da die Korrespondenz \u00fcber Textnachrichten von einem mobilen Gesch\u00e4ftstelefon aus weder im Tarifvertrag noch in den internationalen Bestimmungen des Unternehmens geregelt war, ist der der Arbeitnehmer zu Recht davon auszugehen, dass seine Kommunikation via Textnachricht vertraulich behandelt w\u00fcrde.<\/p>\n<p style=\"text-align: justify;\">Auf der anderen Seite kann argumentiert werden, dass die Sachlage anders w\u00e4re, h\u00e4tte der Arbeitgeber die Verwendung des gesch\u00e4ftlichen Mobiltelefons f\u00fcr private Kommunikation im Voraus verboten oder eingeschr\u00e4nkt. Dann h\u00e4tte f\u00fcr den Arbeitgeber die M\u00f6glichkeit bestanden, den Inhalt der Nachrichten einzusehen und diesen als Beweismittel w\u00e4hrend des Verfahrens zu verwenden. In diesem Fall w\u00e4ren die Textnachrichten eine rechtm\u00e4\u00dfiges Beweismittel zugunsten des Arbeitgebers, wie im Urteil der Handelskammer vom 10. Februar 2015 beschlossen.<\/p>\n<p style=\"text-align: justify;\"><strong>In\u00e8s Ducom &amp; Nicol\u00e1s Melchior<\/strong><\/p>\n<p><strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/a><\/strong><\/p>\n<h2><em><strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die spanischen Gerichte haben unter Erf\u00fcllung gewisser Bedingungen die Kontrolle und \u00dcberwachung der privaten Kommunikation von Mitarbeitern \u00fcber Gesch\u00e4ftscomputer als rechtm\u00e4\u00dfig erkl\u00e4rt. \u00dcber die Frage der Kontrolle von Textnachrichten auf gesch\u00e4ftlichen Mobiltelefonen, wie in einem franz\u00f6sischen Urteil bestimmt, wurde noch nicht durch eine spanische Rechtsprechung beschlossen.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-5007","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>\u00dcberwachung der Arbeitnehmerkommunikation in Spanien<\/title>\n<meta name=\"description\" content=\"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00dcberwachung der Arbeitnehmerkommunikation in Spanien\" \/>\n<meta property=\"og:description\" content=\"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-19T08:00:07+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:15:55+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Regelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer\",\"datePublished\":\"2016-04-19T08:00:07+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/\"},\"wordCount\":687,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/\",\"name\":\"\u00dcberwachung der Arbeitnehmerkommunikation in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2016-04-19T08:00:07+00:00\",\"dateModified\":\"2020-04-11T07:15:55+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Regelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00dcberwachung der Arbeitnehmerkommunikation in Spanien","description":"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/","og_locale":"en_US","og_type":"article","og_title":"\u00dcberwachung der Arbeitnehmerkommunikation in Spanien","og_description":"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2016-04-19T08:00:07+00:00","article_modified_time":"2020-04-11T07:15:55+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Regelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer","datePublished":"2016-04-19T08:00:07+00:00","dateModified":"2020-04-11T07:15:55+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/"},"wordCount":687,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/","name":"\u00dcberwachung der Arbeitnehmerkommunikation in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2016-04-19T08:00:07+00:00","dateModified":"2020-04-11T07:15:55+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"Die spanischen Gerichte erlauben unter gewissen Bedingungen die \u00dcberwachung der Kommunikation (SMS, Anrufe, Email) der Arbeitnehmer.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/regelungen-zur-uberwachung-der-kommunikation-der-arbeitnehmer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Regelungen zur \u00dcberwachung der Kommunikation der Arbeitnehmer"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=5007"}],"version-history":[{"count":2,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5007\/revisions"}],"predecessor-version":[{"id":6610,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/5007\/revisions\/6610"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=5007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=5007"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=5007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}