{"id":4216,"date":"2015-01-27T08:00:40","date_gmt":"2015-01-27T08:00:40","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=4216"},"modified":"2020-04-11T07:23:01","modified_gmt":"2020-04-11T07:23:01","slug":"praktische-aspekte-des-immobilienkaufs-in-spanien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/","title":{"rendered":"Praktische Aspekte des Immobilienkaufs in Spanien"},"content":{"rendered":"<p>Der Immobilienerwerb in Spanien ist ein einfacher Prozess. Das Rechtssystem gew\u00e4hrt beiden Parteien eine gewisse Sicherheit, wenn der Kaufsprozess ordentlich gef\u00fchrt wird.<\/p>\n<p>Es gibt keine Beschr\u00e4nkungen oder Begrenzungen der H\u00f6he der Investitionen, die von Nicht-Spaniern in Spanien gemacht werden d\u00fcrfen; hier gilt die spanische Investitionsfreiheit.<\/p>\n<p>Im Folgenden werden die wesentlichen Schritte aufgef\u00fchrt, die im Anschluss an die Auswahl des Immobilie durchgef\u00fchrt werden m\u00fcssen.<!--morePraktische Aspekte des Immobilienkaufs in Spanien--><\/p>\n<p><a href=\"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien.png\"><img loading=\"lazy\" decoding=\"async\" class=\"wp-image-3715  aligncenter\" src=\"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\" alt=\"In 4 Schritten zum Hauskauf in Spanien\" width=\"383\" height=\"508\" \/><\/a><\/p>\n<h2><span style=\"color: #000080;\"><em><strong>Vorabpr\u00fcfungen<\/strong><\/em><\/span><\/h2>\n<p><span style=\"color: #000080;\">\u00a0<\/span><\/p>\n<p>Zun\u00e4chst m\u00fcssen die Besitzverh\u00e4ltnisse und m\u00f6gliche Aufwendungen der Immobilie \u00fcberpr\u00fcft werden.<\/p>\n<p>Es wird empfohlen, die im Grundbuch stehende Situation der Immobilie zu verifizieren sowie entsprechende Titel des Verk\u00e4ufers.<\/p>\n<p>Man braucht au\u00dferdem eine Zertifikat des St\u00e4dtebauwesens; diese Lizenz h\u00e4ngt davon ab, wof\u00fcr die Immobilie genutzt werden soll. Aber auch die Tatsache, ob entsprechende Zahlungsverpflichtungen erf\u00fcllt wurden, beeinflussen die Ausstellungen des Nachweises.<\/p>\n<p>Ein Anwalt mit Erfahrung im Immobilienerwerb sollte diese \u00dcberpr\u00fcfungen vornehmen.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000080;\"><em><strong>Anzahlungsvertrag<\/strong><\/em><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Im Allgemeinen wird ein Anzahlungsvertrag unterschrieben; dies hat den Zweck, f\u00fcr den K\u00e4ufer den m\u00f6glichen Verkauf der Immobilie an andere zu verhindern und sichert f\u00fcr den Verk\u00e4ufer den Verkauf ab.<\/p>\n<p>Erf\u00fcllt eine der beiden Parteien seine Anwesenheitspflicht zur Unterzeichnung des Kaufvertrags nicht, werden entsprechende Strafen erhoben. Gegebenenenfalls kann der K\u00e4ufer die von ihm angezahlte Summe verlieren, wenn dies im Voraus so vereinbart wurde.<\/p>\n<p>Die \u00dcberpf\u00fcfung des Kaufvertrages sollte einem Anwalt \u00fcberlassen werden, um die Interessen der Unterzeichner zu sch\u00fctzen.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000080;\"><em><strong>Notarielle Beurkundung<\/strong><\/em><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Der Immobilienkauf muss durch notarielle Beurkundung erfasst werden, damit die Eigentums\u00fcbertragung im Grundbuch erfasst und gesch\u00fctzt werden kann. Die Voraussetzung daf\u00fcr ist, dass der \u00a0Kaufvertrag von einem spanischen Notar unterzeichnet wird. Dieser wird die Identit\u00e4t und Rechtsf\u00e4higkeit der Unterzeichner best\u00e4tigen.<\/p>\n<p>Die Anw\u00e4lte koordinieren und \u00fcberpr\u00fcfen die Vorbereitung der Beeurkundung durch das Notariat.<\/p>\n<p>Diese Beurkundung kann von den Parteien pers\u00f6nlich, oder durch eine Vollmacht mit allen n\u00f6tigen Formvorschriften erfolgen. Durch die Unterschrift vor dem Notar entstehen entsprechende Steuern Notargeb\u00fchren.<\/p>\n<p>&nbsp;<\/p>\n<h2><span style=\"color: #000080;\"><em><strong>Unterschrift und Steuern<\/strong><\/em><\/span><\/h2>\n<p>&nbsp;<\/p>\n<p>Nach Unterschrift der Urkunde m\u00fcssen folgende Steuern bezahlt werden. Die H\u00f6he der Steuer ist abh\u00e4ngig davon, ob es sich um eine Immobilie mit Erstbezug handelt, oder um eine Immobilie, die bereits bewohnt war.<\/p>\n<ul>\n<li>Neue Immobilie, die von einer jurisitschen Person verkauft wird: Der K\u00e4ufer muss die MWSt in H\u00f6he eines Steuersatz von 10% zahlen; abgesehen von einigen autonomen Gemeinschaften, in denen niedrigere Steuers\u00e4tze anfallen. Au\u00dferdem muss der K\u00e4ufer eine Dokumentabgabesteuer zahlen. Diese ist in jeder autonomen Gemeinschaft unterschiedlich und reicht von einem Minimum von 0,1% bis zu maximal 1,5%. Der K\u00e4ufer zahlt also h\u00f6chstens 11,5% Steuern auf den Immobilienkauf.<\/li>\n<\/ul>\n<ul>\n<li>Gebrauchte Immobiliee: Der K\u00e4ufer muss die Steuer auf verm\u00f6gensrechtliche \u00dcbertragungen zahlen, deren Steuersatz zwischen 6% und 10% liegt, je nach autonomer Gemeinschaft.<\/li>\n<\/ul>\n<p>Au\u00dferdem muss der Verk\u00e4ufer die Steuer auf die Wertsteigerung der Immobilie bezahlen.<\/p>\n<p>Jede Gemeinde kann ihre eigenen Normen anwenden, um die Berechnung dieser Steuer festzulgen. Der maximale Steuersatz liegt bei 30%. Die Parteien k\u00f6nnen sich darauf einigen, dass diese Steuer vom K\u00e4ufer zu zahlen ist. Die lokalen Regelungen k\u00f6nnen den Verk\u00e4ufer zur Zahlung dieser Steuer zwingen, wenn es sich bei der zu verkaufenden Immobilie nicht um seinen Hauptwohnsitz handelt. Daher ist es sehr wichtig, dieses Thema im Voraus abzukl\u00e4ren.<\/p>\n<p>Im Anschluss sollte die Beurkundung im Grundbuchregister eingetragen werden, wodurch weitere Registergeb\u00fchren entstehen k\u00f6nnen.<\/p>\n<p>Ist der K\u00e4ufer oder Verk\u00e4ufer Nicht-Spanier, muss eine entsprechende Mitteilung \u00fcber den Kaufvorgang an das Wirtschaftsministerium erfolgen. Das Ministerium f\u00fchrt eine Kontrolle von Investitionen und Ver\u00e4usserungen rein zu statistischen Zwecken. Dennoch kann die Nichterf\u00fcllung dieser Mitteilungspflicht eine Strafe nach sich ziehen.<\/p>\n<p>&nbsp;<\/p>\n<p><strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\">Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/a><\/strong><\/p>\n<h2><em><strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Der Immobilienerwerb in Spanien ist ein einfacher Prozess. Das Rechtssystem gew\u00e4hrt beiden Parteien eine gewisse Sicherheit, wenn der Kaufsprozess ordentlich gef\u00fchrt wird. Es gibt keine Beschr\u00e4nkungen oder Begrenzungen der H\u00f6he der Investitionen, die von Nicht-Spaniern in Spanien gemacht werden d\u00fcrfen; hier gilt die spanische Investitionsfreiheit. Im Folgenden werden die wesentlichen Schritte aufgef\u00fchrt, die im Anschluss [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-4216","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Immobilienkauf in Spanien<\/title>\n<meta name=\"description\" content=\"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Immobilienkauf in Spanien\" \/>\n<meta property=\"og:description\" content=\"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-27T08:00:40+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:23:01+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Praktische Aspekte des Immobilienkaufs in Spanien\",\"datePublished\":\"2015-01-27T08:00:40+00:00\",\"dateModified\":\"2020-04-11T07:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/\"},\"wordCount\":639,\"image\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\",\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/\",\"name\":\"Immobilienkauf in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#primaryimage\"},\"image\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#primaryimage\"},\"thumbnailUrl\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\",\"datePublished\":\"2015-01-27T08:00:40+00:00\",\"dateModified\":\"2020-04-11T07:23:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"description\":\"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#primaryimage\",\"url\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\",\"contentUrl\":\"http:\\\/\\\/www.mariscal-abogados.de\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/praktische-aspekte-des-immobilienkaufs-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Praktische Aspekte des Immobilienkaufs in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Immobilienkauf in Spanien","description":"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Immobilienkauf in Spanien","og_description":"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2015-01-27T08:00:40+00:00","article_modified_time":"2020-04-11T07:23:01+00:00","og_image":[{"url":"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png","type":"","width":"","height":""}],"author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Praktische Aspekte des Immobilienkaufs in Spanien","datePublished":"2015-01-27T08:00:40+00:00","dateModified":"2020-04-11T07:23:01+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/"},"wordCount":639,"image":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#primaryimage"},"thumbnailUrl":"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png","articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/","name":"Immobilienkauf in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"primaryImageOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#primaryimage"},"image":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#primaryimage"},"thumbnailUrl":"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png","datePublished":"2015-01-27T08:00:40+00:00","dateModified":"2020-04-11T07:23:01+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"description":"Mit der richtigen juristischen Beratung ist der Immobilienkauf in Spanien durch Nicht-Spanier ein einfacher Prozess.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#primaryimage","url":"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png","contentUrl":"http:\/\/www.mariscal-abogados.de\/wp-content\/uploads\/2014\/10\/In-4-Schritten-zum-Hauskauf-in-Spanien-226x300.png"},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/praktische-aspekte-des-immobilienkaufs-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Praktische Aspekte des Immobilienkaufs in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=4216"}],"version-history":[{"count":3,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4216\/revisions"}],"predecessor-version":[{"id":6462,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4216\/revisions\/6462"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=4216"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=4216"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=4216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}