{"id":4182,"date":"2015-01-23T08:00:11","date_gmt":"2015-01-23T08:00:11","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=4182"},"modified":"2020-04-11T07:23:01","modified_gmt":"2020-04-11T07:23:01","slug":"der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/","title":{"rendered":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien"},"content":{"rendered":"<p>Wer in eine Immobilie in Spanien investiert, sollte davon ausgehen k\u00f6nnen, dass der von ihm gezahlte Kaufpreis mit dem in der Kaufurkunde angegebenen Wert \u00fcbereinstimmen muss. Im Laufe der Jahre haben sich jedoch je nach Konjunkturlage und der Haltung der Steuerbeh\u00f6rden sehr unterschiedliche Situationen ergeben.<!--moreDer Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien--><\/p>\n<p>Denjenigen, die vor dem Platzen der Immobilienblase 2008 eine Immobilie gekauft haben, ist wahrscheinlich der Vorschlag bekannt, in der Kaufurkunde einen niedrigeren Preis anzugeben, als der, der tats\u00e4chlich gezahlt wurde. Diese Vorgehensweise war seinerzeit weit verbreitet, um dem K\u00e4ufer und dem Verk\u00e4ufer Steuern einzusparen. So zahlte dann der K\u00e4ufer weniger Verm\u00f6gens\u00fcbertragungssteuer in seiner Eigenschaft als Erwerbender, da diese auf der Grundlage des Kaufpreises berechnet wird; aber auch der Verk\u00e4ufer zahlte weniger, da der Verm\u00f6genszuwachs durch den Verkauf geringer war und somit auch die von ihm zu zahlende Einkommensteuer.<\/p>\n<p>Die Zeiten \u00e4ndern sich und, wer h\u00e4tte das gedacht, heute ist die Lage genau umgekehrt. Die derzeitige katastrophale Situation des Immobilienmarktes kann dazu f\u00fchren, dass K\u00e4ufer und Verk\u00e4ufer einen h\u00f6heren Wert als den tats\u00e4chlich gezahlten Wert angeben, um eine Pr\u00fcfung durch das Finanzamt zu vermeiden. Denn unabh\u00e4ngig vom tats\u00e4chlich gezahlten Preis ist der Referenzwert f\u00fcr das Finanzamt ein von vornherein feststehender Wert, der sogenannte \u201csteuerliche Wert\u201d. Dieser Wert kann f\u00fcr jeden konkreten Fall ausgehend von dem durch das Finanzamt f\u00fcr die Immobilie nach verschiedenen objektiven Faktoren bestimmten Wert berechnet werden. Einige Gemeinden haben in den goldenen Jahren vor 2008 die Katasterwerte der Immobilien ihrer Region aktualisiert und sie ganz nach dem Vorbild der spektakul\u00e4ren Entwicklung der Immobilienpreise erh\u00f6ht. Sind die Katasterwerte einer Gemeinde einmal ge\u00e4ndert, ist eine neue Modifizierung nicht einfach. Zudem sind hierzu gesetzliche Fristen einzuhalten, durch die eine erneute Aktualisierung um einige Jahre hinausgez\u00f6gert wird. Aus diesem Grund treffen wir heute teilweise auf Katasterwerte, die vor dem Platzen der Immobilienblase aktualisiert wurden und aus denen sich Mindeststeuerwerte ergeben, die \u00fcber dem durchschnittlichen Marktpreis liegen.<\/p>\n<p>Wird dieser steuerliche Wert beim Abschluss des Kaufvertrags in einer notariellen Urkunde nicht in Betracht gezogen, erfolgt mit gr\u00f6\u00dfter Sicherheit eine Inspektion durch die Steuerbeh\u00f6rde, vor der es sicher schwer nachzuweisen ist, dass nicht mehr gezahlt wurde, als in der Urkunde angegeben wurde, auch wenn der angegebene Preis dem tats\u00e4chlich gezahlten Preis entspricht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Carlos Prieto Cid, Rechtsanwalt<\/strong><br \/>\n<a title=\"Tarracoiuris Abogados, Spanish Lawyers in Tarragona, Spain\" href=\"http:\/\/www.tarracoiuris-abogados.com\/\" target=\"_blank\" rel=\"noopener noreferrer\">Tarracoiuris Abogados, deutschsprachige Rechtsanw\u00e4lte in Tarragona, Spain<\/a><\/p>\n<h2><em><strong>Member of Eurojuris Espa\u00f1a, <\/strong><\/em><strong><em>Internationales Netzwerk von Spanischen Anwaltskanzleien<\/em><\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Wer in eine Immobilie in Spanien investiert, sollte davon ausgehen k\u00f6nnen, dass der von ihm gezahlte Kaufpreis mit dem in der Kaufurkunde angegebenen Wert \u00fcbereinstimmen muss. Im Laufe der Jahre haben sich jedoch je nach Konjunkturlage und der Haltung der Steuerbeh\u00f6rden sehr unterschiedliche Situationen ergeben.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-4182","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a\" \/>\n<meta property=\"og:description\" content=\"Wer in eine Immobilie in Spanien investiert, sollte davon ausgehen k\u00f6nnen, dass der von ihm gezahlte Kaufpreis mit dem in der Kaufurkunde angegebenen Wert \u00fcbereinstimmen muss. Im Laufe der Jahre haben sich jedoch je nach Konjunkturlage und der Haltung der Steuerbeh\u00f6rden sehr unterschiedliche Situationen ergeben.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2015-01-23T08:00:11+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:23:01+00:00\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"headline\":\"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien\",\"datePublished\":\"2015-01-23T08:00:11+00:00\",\"dateModified\":\"2020-04-11T07:23:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/\"},\"wordCount\":425,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/\",\"name\":\"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2015-01-23T08:00:11+00:00\",\"dateModified\":\"2020-04-11T07:23:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/b3fb8da5509c2814d015012a9295e5dd\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g\",\"caption\":\"admin\"},\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/","og_locale":"en_US","og_type":"article","og_title":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a","og_description":"Wer in eine Immobilie in Spanien investiert, sollte davon ausgehen k\u00f6nnen, dass der von ihm gezahlte Kaufpreis mit dem in der Kaufurkunde angegebenen Wert \u00fcbereinstimmen muss. Im Laufe der Jahre haben sich jedoch je nach Konjunkturlage und der Haltung der Steuerbeh\u00f6rden sehr unterschiedliche Situationen ergeben.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2015-01-23T08:00:11+00:00","article_modified_time":"2020-04-11T07:23:01+00:00","author":"admin","twitter_card":"summary_large_image","twitter_misc":{"Written by":"admin","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/"},"author":{"name":"admin","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"headline":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien","datePublished":"2015-01-23T08:00:11+00:00","dateModified":"2020-04-11T07:23:01+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/"},"wordCount":425,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/","name":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien - Eurojuris Espa\u00f1a","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2015-01-23T08:00:11+00:00","dateModified":"2020-04-11T07:23:01+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd"},"breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/der-unterschied-zwischen-preis-und-steuerlichem-wert-beim-kauf-von-immobilien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Der Unterschied zwischen Preis und steuerlichem Wert beim Kauf von Immobilien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/b3fb8da5509c2814d015012a9295e5dd","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e395eb845ace2468002188d4d92f068d8124531cf8d8f3bcaf5f839f3eb10e3c?s=96&d=blank&r=g","caption":"admin"},"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/admin\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4182","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=4182"}],"version-history":[{"count":2,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4182\/revisions"}],"predecessor-version":[{"id":6463,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/4182\/revisions\/6463"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=4182"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=4182"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=4182"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}