{"id":3609,"date":"2014-05-21T08:00:33","date_gmt":"2014-05-21T08:00:33","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=3609"},"modified":"2020-04-11T07:21:08","modified_gmt":"2020-04-11T07:21:08","slug":"neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/","title":{"rendered":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien"},"content":{"rendered":"<p>Die spanische Regierung versucht durch verschiedene Ma\u00dfnahmen, die wirtschaftliche Krise der letzten Jahre zu \u00fcberwinden. Hierbei sind staatliche Investitionen ein wichtiges Instrument. Durch sie soll ein attraktives Investitionsklima geschaffen und so private Investitionen gef\u00f6rdert werden. Zu diesem Zweck hat der Pr\u00e4sident der spanischen Regierung Mariano Rajoy einen \u201ePlan f\u00fcr wirtschaftliches Wachstum und der Unterst\u00fctzung von Unternehmern\u201c (Plan de Est\u00edmulo Econ\u00f3mico y Apoyo al Emprendedor) vorgestellt, der verschiedenen Ma\u03b2nahmen vorsieht, unter ihnen ein neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien.<\/p>\n<h2><!--moreNeues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien--><em><strong><span style=\"color: #000080;\">FOND-ICO Global<\/span><\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>Im Zuge dieses Vorhabens wurde mit dem \u201eFOND-ICO Global\u201c am 24. Mai 2013 der erste \u00f6ffentliche Dachfond (\u201efund of funds\u201c) Spaniens geschaffen, der von AXIS, der Gesellschaft f\u00fcr Risikokapital des \u201eInstituto de Cr\u00e9dito Oficial\u201c (ICO, eine dem Finanzministerium unterstehende staatliche Finanzierungsagentur, die das Pendant zur KfW darstellt) geleitet wird. Dieser Fond ist mit einem Kapitalvolumen von 1.200 Millionen Euro ausgestattet, das allein der F\u00f6rderung von Investitionen durch Risikokapitalfonds dienen soll.<\/p>\n<p>Mit der im Oktober erfolgten ersten \u00f6ffentlichen Ausschreibung von finanziellen Mitteln aus diesem Fond ist das Projekt in seine Anfangsphase eingetreten. Ziel ist es dabei, das Image Spaniens im Ausland zu verbessern und ausl\u00e4ndische Investitionen in spanische Unternehmen zu f\u00f6rdern. Ein solches Interesse ausl\u00e4ndischer Firmen und ein allgemein gro\u03b2es Interesse an Investitionen in Spanien seien laut dem Leiter des ICO, Herr Rom\u00e1n Escolano, aktuell feststellbar. Zudem sollen so bestehende Investitionsquellen verbessert und neue erschlossen werden, Arbeitspl\u00e4tze geschaffen, die Attraktivit\u00e4t f\u00fcr internationale Investoren erh\u00f6ht und die Internationalisierung spanischer Unternehmen bef\u00f6rdert werden.<\/p>\n<p>AXIS hat zu diesem Zweck ein Investitionsprogramm geschaffen, das Ausschreibungen zur Vergabe von Kapital in regelm\u00e4\u03b2igen zeitlichen Abst\u00e4nden vorsieht. An diesen regelm\u00e4\u03b2igen Ausschreibungen k\u00f6nnen alle Fonds teilnehmen, die die jeweiligen Ausschreibungsvoraussetzungen erf\u00fcllen. Dieses Programm erlaubt es, dass der finanzielle Beitrag des Dachfonds als \u201eInvestitionsanker\u201c dient und sowohl nationale als auch internationale Investoren anzieht. Es sind verschiedene Ausschreibungen in den n\u00e4chsten vier Jahren vorgesehen, die fortlaufend an den Bedarf der Investoren sowie an die jeweilige Marktsituation angepasst werden sollen. Laut einer Pressemitteilung des ICO wird gesch\u00e4tzt, dass der FOND-ICO Global so an der Schaffung von mehr als 40 neuen Risikokapitalfonds beteiligt sein wird und ein Kapital von bis zu 3000 Millionen Euro mobilisieren kann.<\/p>\n<p>&nbsp;<\/p>\n<h2><em><strong><span style=\"color: #000080;\">Erste Erfahrungswerte<\/span><\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>In der ersten Ausschreibung, deren Bewerbungsfrist am 31. Oktober 2013 abgelaufen ist, wurden 600 Millionen Euros an sechs Fonds vergeben, die in Spanien registriert sind und die einen Teil des Fondskapitals zur Investition in Spanien einsetzen, unabh\u00e4ngig davon ob das Kapital im Bereich der Neugr\u00fcndung oder der Entwicklung von Unternehmen eingesetzt wird. Dabei wird nicht das ICO den Hauptteil der Investitionen tragen, sondern maximal 30-40 % des Kapital stellen, abh\u00e4ngig davon, ob das Kapital an ein Fond geht, der die Erweiterung bzw. Entwicklung eines Unternehmens finanziert oder die \u2013 mit gr\u00f6\u03b2eren Risiken verbundene \u2013 Neugr\u00fcndung. Zudem h\u00e4ngt das Kapitalvolumen von der Gr\u00f6\u03b2e des Fonds ab. Diese erhebliche Summe schon der ersten Ausschreibung ist dabei h\u00f6her als die gesamten Investitionen in Spanien im Bereich des Risikokapitals von Januar bis Juni diesen Jahres.<\/p>\n<p>&nbsp;<\/p>\n<h2><em><strong><span style=\"color: #000080;\">Ausschreibung<\/span><\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>Die erste Ausschreibung bezieht sich auf zwei Bereiche: Wachstums- und Risikokapital. In jedem der beiden Bereiche werden bis zu drei Fonds ausgew\u00e4hlt und finanziell unterst\u00fctzt. Dabei enth\u00e4lt die Ausschreibung die folgenden Regelungen:<\/p>\n<ol>\n<li>Der Teilnehmerkreis wird von der Ausschreibung festgelegt und umfasst zum einen Wachstumskapitalfonds und zum anderen Risikokapitalfonds. Unter ersteren sind solche Fonds zu verstehen, die zwischen 2 und 100 Millionen Euro in Gesch\u00e4ftsanteile von bereits seit drei Jahren bestehenden, aber nicht b\u00f6rsennotierten Unternehmen investieren. Unter letzteren sind solche zu verstehen, die zwischen 250.000 und 10 Millionen Euro in Gesch\u00e4ftsanteile von bereits seit f\u00fcnf Jahren bestehenden, aber nicht b\u00f6rsennotierten Unternehmen investieren.<\/li>\n<li>In beiden Bereichen sollen Betreiber, die rein privaten Fonds (ohne irgendeine direkte oder indirekte Beteiligung der \u00f6ffentlichen Hand) leiten und Interesse an der Investition in spanische Unternehmen haben, gef\u00f6rdert werden, da Voraussetzung ist, dass mindestens 50 % des Fondkapitals oder das wenigstens das Doppelte des von dem FOND-ICO Global zur Verf\u00fcgung gestellten Betrags in spanische Unternehmen investiert wird. Zudem muss der Fond ein Minimum von drei Investoren neben Fond-ICO Global beim ersten Gesch\u00e4ftsschluss aufweisen und zumindest die verbindliche Zusage von anderen Investoren in H\u00f6he von mindestens 20% des Zielkapitals vor Entscheidung des Auswahlkomitees des Fond-ICO Global vorweisen k\u00f6nnen. In diese Fonds d\u00fcrfen bereits Fond-ICO Pyme und\/oder Neotec (zwei weitere staatliche Finanzierungsfonds) investiert haben, solange der Fond die aufgestellten Voraussetzungen erf\u00fcllt und der geregelte Maximalbetrag nicht \u00fcberschritten wird.<\/li>\n<li>Im Bereich des Wachstumskapitals kann FOND-ICO Global in jeden ausgew\u00e4hlten Fond bis zu 30% dessen Zielkapitals investieren mit einem Maximalbetrag von 70 Millionen Euro und maximal das 15fache des versprochenen Investitionskapitals des Fonds. Im Bereich des Risikokapitals kann FOND-ICO Global in jeden ausgew\u00e4hlten Fond bis zu 40% dessen Zielkapitals investieren mit einem Maximalbetrag von 20 Millionen Euro und maximal das 20fache des versprochenen Investitionskapitals des Fonds.<\/li>\n<\/ol>\n<p>&nbsp;<\/p>\n<h2><em><strong><span style=\"color: #000080;\">Auswahlverfahren<\/span><\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>Der Ablauf des Auswahlverfahrens ist wiederum f\u00fcr beide Bereiche identisch und ist wie folgt: zun\u00e4chst ist eine Qualifikationsphase geplant, innerhalb derer die Unternehmen darlegen m\u00fcssen, dass sie die hier aufgef\u00fchrten Voraussetzungen erf\u00fcllen. Dabei sind alle erforderlichen Unterlagen pers\u00f6nlich bei AXIS PARTICIPACIONES EMPRESARIALES SGECR, S.A.U. im Registro General de Axis (C\/ Los Madrazo 38, 28014, Madrid) einzureichen. Im Anschluss folgt die Bewertung der abgegebenen Angebote der Unternehmen, die sich in der ersten Phase qualifiziert haben, in der die drei Fonds mit den besten Beurteilungen ausgew\u00e4hlt werden.<\/p>\n<p>&nbsp;<\/p>\n<h2><em><strong><span style=\"color: #000080;\">Schlussfolgerung<\/span><\/strong><\/em><\/h2>\n<p>&nbsp;<\/p>\n<p>Die Schaffung dieses Programm mit einem Investitionsvolumen von 1.200 Millionen Euro stellt sicherlich einen weiteren Schritt Spaniens aus der Krise dar und ist zudem eine besondere Gelegenheit f\u00fcr interessierte Investoren. Diese und die folgenden Ausschreiben werden jeweils auf der Website http:\/\/www.axispart.com\/ ver\u00f6ffentlicht.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Karl H. Lincke<\/strong><br \/>\n<span style=\"color: #000080;\"><strong><a title=\"Mariscal Abogados, Rechtsanw\u00e4lte\" href=\"http:\/\/www.mariscal-abogados.de\/\" target=\"_blank\" rel=\"noopener noreferrer\"><span style=\"color: #000080;\"><strong>Mariscal Abogados, Rechtsanw\u00e4lte Madrid, Spanien<\/strong><\/span><\/a><\/strong><\/span><\/p>\n<h2><span style=\"color: #000080;\"><em><strong>Eurojuris Espa\u00f1a, Netzwerk von Spanischen Anwaltskanzleien<\/strong><\/em><\/span><\/h2>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Die spanische Regierung versucht durch verschiedene Ma\u00dfnahmen, die wirtschaftliche Krise der letzten Jahre zu \u00fcberwinden. Hierbei sind staatliche Investitionen ein wichtiges Instrument. Durch sie soll ein attraktives Investitionsklima geschaffen und so private Investitionen gef\u00f6rdert werden. Zu diesem Zweck hat der Pr\u00e4sident der spanischen Regierung Mariano Rajoy einen \u201ePlan f\u00fcr wirtschaftliches Wachstum und der Unterst\u00fctzung von [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[],"class_list":["post-3609","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien<\/title>\n<meta name=\"description\" content=\"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien\" \/>\n<meta property=\"og:description\" content=\"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.\" \/>\n<meta property=\"og:url\" content=\"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2014-05-21T08:00:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:21:08+00:00\" \/>\n<meta name=\"author\" content=\"Laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/#article\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/\"},\"author\":{\"name\":\"Laura\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"headline\":\"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien\",\"datePublished\":\"2014-05-21T08:00:33+00:00\",\"dateModified\":\"2020-04-11T07:21:08+00:00\",\"mainEntityOfPage\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/\"},\"wordCount\":996,\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/\",\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/\",\"name\":\"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2014-05-21T08:00:33+00:00\",\"dateModified\":\"2020-04-11T07:21:08+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"description\":\"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"caption\":\"Laura\"},\"sameAs\":[\"http:\\\/\\\/\"],\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien","description":"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/","og_locale":"en_US","og_type":"article","og_title":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien","og_description":"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.","og_url":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2014-05-21T08:00:33+00:00","article_modified_time":"2020-04-11T07:21:08+00:00","author":"Laura","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/#article","isPartOf":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/"},"author":{"name":"Laura","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"headline":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien","datePublished":"2014-05-21T08:00:33+00:00","dateModified":"2020-04-11T07:21:08+00:00","mainEntityOfPage":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/"},"wordCount":996,"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/","url":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/","name":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2014-05-21T08:00:33+00:00","dateModified":"2020-04-11T07:21:08+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"description":"Ein Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien ist bei dem \u201ePlan f\u00fcr die Unterst\u00fctzung von Unternehmern\u201c vorgestellt.","breadcrumb":{"@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/www.asociacion-eurojuris.es\/en\/neues-gesetzesprojekt-zur-forderung-der-investitionen-von-risikokapitalfonds-in-spanien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Neues Gesetzesprojekt zur F\u00f6rderung der Investitionen von Risikokapitalfonds in Spanien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed","name":"Laura","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","caption":"Laura"},"sameAs":["http:\/\/"],"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/laura\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/3609","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=3609"}],"version-history":[{"count":5,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/3609\/revisions"}],"predecessor-version":[{"id":6426,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/3609\/revisions\/6426"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=3609"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=3609"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=3609"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}