{"id":1443,"date":"2012-01-19T08:00:30","date_gmt":"2012-01-19T08:00:30","guid":{"rendered":"http:\/\/www.asociacion-eurojuris.es\/en\/?p=1443"},"modified":"2020-04-11T07:20:36","modified_gmt":"2020-04-11T07:20:36","slug":"die-rolle-des-anwalts-beim-verkauf-von-immobilien","status":"publish","type":"post","link":"http:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/","title":{"rendered":"Die Rolle des Anwalts beim Verkauf von Immobilien"},"content":{"rendered":"<p>In den goldenen Jahren der Immobilienblase, wenn alles gut angekauft wurde, spielten <strong>Juristen eine wesentliche Rolle in der Beratung von K\u00e4ufern<\/strong>, damit diese Eigentum von Inmobilien mit voller Garantie erwerben konnten. Jetzt, da alles verkauft wird, ist unsere Rolle noch wesentlich, um das zu verhindern, dass ein eventueller Verkauf durch rechtlichen Gr\u00fcnden frustriert wird.<!--more-->Ein gew\u00f6hnlicher Mensch nimmt nur wenige Male in seinem Leben die Entscheidung, eine <strong>Immobilie zu kaufen oder zu verkaufen<\/strong>. Allerdings scheint es, als ob es kein Bewusstsein in der Gesellschaft geben w\u00fcrde, dass es ratsam ist, mit <strong>einem Anwalt zu konsultieren<\/strong>, bevor man diese grundlegende Entscheidung nimmt. Ganz im Gegenteil, die allgemeine Idee ist, dass man nur zu einem Anwalt gehen soll, um rechtliche Probleme zu l\u00f6sen und nicht, wie es sein sollte, um das zu versuchen, sie zu vermeiden. Deshalb haben wir<strong> Juristen<\/strong> oft Kunden, die erst zu uns kommen, wenn sie bereits einen Vertrag unterzeichnet haben, mit der Hoffnung, dass wir mit einem Zauberstab eine problematische Situation l\u00f6sen k\u00f6nnen, die niemals stattgefunden h\u00e4tte, wenn sie uns rechtzeitig konsultiert h\u00e4tten.<\/p>\n<p>Unter den Fachleuten, die am Entscheidungsprozess der Unterschrift eines <strong>Immobilien-Kaufvertrages<\/strong> beteiligt sind, ist der Anwalt der einzige, der Beratung mit der Garantie geben kann, dass dies nur seine Rolle ist und dass er ausschliesslich deshalb bezahlt worden ist. Er beratet, mit der absoluten Unabh\u00e4ngigkeit desjenigen, der wei\u00df, das sein Honorar sowieso bezahlt wird, auch wenn die Operation nicht durchgef\u00fchrt wird. Kurz gesagt, <strong>der Anwalt ist der einzige Fachmann, der ruhig dem Kunden sagen kann: bitte unterschreiben Sie das doch mal nicht!<\/strong> Deshalb ist die Beratung eines Rechtsanwalts vor der Unterzeichnung eines<strong> Immobilienvertrages<\/strong> so wichtig, und je fr\u00fcher man zu ihm kommt, desto besser.<\/p>\n<p>In Immobilienmarkt neigen Vermittler oft dazu, die Intervention von <strong>Anw\u00e4lten <\/strong>zu vermeiden, weil sie davon ausgehen, dass es die Kosten der Transaktion nur erh\u00f6ht und daher wird ihren Handlungsspielraum reduziert. Aber <strong>die Realit\u00e4t ist ganz anders: die Kosten unserer Intervention sind sehr profitabel<\/strong>. Wir k\u00f6nnen tats\u00e4chlich viele Beispiele von <strong>Immobilientransaktionen<\/strong> geben, die niemals h\u00e4tten ausgef\u00fchrt werden k\u00f6nnen, wenn es nicht eine sofortige Intervention der Anw\u00e4lte gewesen w\u00e4re. Die h\u00e4ufigsten Probleme, die wir l\u00f6sen sind:<br \/>\n\u2022 Probleme mit den anwendbaren Eheg\u00fcterstand,<br \/>\n\u2022 die notwendige Formalisierung einer Erbschaftannahme,<br \/>\n\u2022 Geb\u00e4ude wobei eine Erkl\u00e4rung des Neubaus erforderlich ist (auch wenn sie rechtlich gebaut worden, aber im Grundbuch noch nicht registriert, sind)<br \/>\n\u2022 Steuer- und Geldw\u00e4sche-Steuerungsprobleme, die spezifisch gebietsfremde Verk\u00e4ufer oder gebietsfremde K\u00e4ufer betreffen,<br \/>\n\u2022 besondere Verf\u00fcgungsvollmachte, die notwendig sind, um den Vorgang zu formalisieren, wenn einer der Vertragspartner nicht bei der Formalisierung des Kaufvertrages anwesend sein kann&#8230;<\/p>\n<p>\u00a0<\/p>\n<p>Aber die Palette der M\u00f6glichkeiten ist enorm und jeder dieser Fragen kann den <strong>Verkauf beeintr\u00e4chtigen<\/strong> oder sogar unm\u00f6glich machen, besonders in der heutigen Zeit, mit Mangel an K\u00e4ufern und \u00dcberangebot an Wohnungen auf dem Markt. Dar\u00fcber hinaus ist die Erfahrung in internationalen Eigentums\u00fcbertragunsgesch\u00e4ften mit Nicht-Resident-K\u00e4ufer oder Verk\u00e4ufer im Moment entscheidend, da der Immobilienmarkt vor allem sein Angebot potentiellen ausl\u00e4ndischen K\u00e4ufern aus L\u00e4ndern bietet, die heute mehr Kaufkraft und Interesse am Kauf von Immobilien in Spanien haben (Russen, Schweizer, Chinesen, etc.) &#8230;<\/p>\n<p>Der Ausfall einer <strong>Immobilien-Transaktion<\/strong> bedeutet f\u00fcr den betroffenen Immobilien-Makler eine tats\u00e4chliche Ausgabe in Zeit, Hingabe, Reisen und Risikoanalyse, und diese Kosten finden keine Entsch\u00e4digung, wenn der Betrieb am Ende nicht durchgef\u00fchrt wird. Die Ursachen f\u00fcr ein solches Versagen sind oft rechtliche Probleme, die nur ein Fachanwalt fr\u00fch genug vorsehen k\u00f6nnte, der m\u00f6gliche L\u00f6sungen empfehlen k\u00f6nnte um den Verlust des K\u00e4ufers zu vermeiden. Auch wenn keine der vorgeschlagenen L\u00f6sungen angenommen w\u00fcrde, konnte der Anwalt beraten, das Gesch\u00e4ft rechtzeitig zu verlassen, bevor man weitere unn\u00f6tigen Kosten tragen muss. Das Zusammenarbeiten zwischen Anw\u00e4lten und Immobilienmaklern oder anderen Vermittlern auf dem Wohnungsmarkt ist eine wichtige Gesch\u00e4ftsgelegenheit und die Synergien, die es erzeugt, sind sehr hilfreich, sowohl f\u00fcr die Anw\u00e4lte als auch f\u00fcr die beteiligten Makler, da beide ihrem gemeinsamen Kunden das anbieten, mit Garantien kaufen oder verkaufen zu k\u00f6nnen und seine Entscheidung mit allen notwendigen Informationen zu reifen.<\/p>\n<p><strong>Carlos Prieto Cid<\/strong><br \/>\n<a title=\"Tarracoiuris, Rechtsanw\u00e4lte in Tarragona, Spanien\" href=\"http:\/\/www.tarracoiuris-abogados.com\" target=\"_blank\" rel=\"noopener noreferrer\">Tarracoiuris Rechtsanw\u00e4lte<\/a><br \/>\n<span style=\"color: #000080;\"><a title=\"Eurojuris Espa\u00f1a, internationales Netzwerk von Anwaltskanzleien\" href=\"http:\/\/asociacion-eurojuris.es\" target=\"_blank\" rel=\"noopener noreferrer\"><strong>Eurojuris Espa\u00f1a<\/strong><\/a><strong>, intenationales Netzwerk von Anwaltskanzleien<\/strong><\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>In den goldenen Jahren der Immobilienblase, wenn alles gut angekauft wurde, spielten Juristen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben konnten. Jetzt, da alles verkauft wird, ist unsere Rolle noch wesentlich, um das zu verhindern, dass ein eventueller Verkauf durch rechtlichen Gr\u00fcnden frustriert wird.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[210],"tags":[305,7,779,777,780,778,373,375,776,374,296,304,203],"class_list":["post-1443","post","type-post","status-publish","format-standard","hentry","category-veroffentichungen","tag-deutschsprachige-rechtsanwalte-spanien","tag-eurojuris-espana","tag-immobilien-kaufvertrages-spanien","tag-immobilienkauf-beratung","tag-immobilientransaktionen-spanien","tag-immobilienverkauf-beratung-spanien","tag-insolvezrecht-spanien","tag-it-recht-spanien","tag-juristen-spanien","tag-prozessrecht-spanien","tag-rechtsanwalte-tarragona","tag-spanische-rechtsanwalte","tag-tarracoiuris-rechtsanwalte"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Die rolle der Anwalt<\/title>\n<meta name=\"description\" content=\"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Die rolle der Anwalt\" \/>\n<meta property=\"og:description\" content=\"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/\" \/>\n<meta property=\"og:site_name\" content=\"Eurojuris Espa\u00f1a\" \/>\n<meta property=\"article:published_time\" content=\"2012-01-19T08:00:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-04-11T07:20:36+00:00\" \/>\n<meta name=\"author\" content=\"Laura\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Laura\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/\"},\"author\":{\"name\":\"Laura\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"headline\":\"Die Rolle des Anwalts beim Verkauf von Immobilien\",\"datePublished\":\"2012-01-19T08:00:30+00:00\",\"dateModified\":\"2020-04-11T07:20:36+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/\"},\"wordCount\":726,\"keywords\":[\"deutschsprachige rechtsanw\u00e4lte spanien\",\"Eurojuris Espa\u00f1a\",\"immobilien kaufvertrages spanien\",\"immobilienkauf beratung\",\"immobilientransaktionen spanien\",\"immobilienverkauf beratung spanien\",\"insolvezrecht spanien\",\"it recht spanien\",\"juristen spanien\",\"prozessrecht spanien\",\"rechtsanw\u00e4lte tarragona\",\"spanische rechtsanw\u00e4lte\",\"tarracoiuris rechtsanw\u00e4lte\"],\"articleSection\":[\"Ver\u00f6ffentichungen\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/\",\"name\":\"Die rolle der Anwalt\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\"},\"datePublished\":\"2012-01-19T08:00:30+00:00\",\"dateModified\":\"2020-04-11T07:20:36+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\"},\"description\":\"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Die Rolle des Anwalts beim Verkauf von Immobilien\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/\",\"name\":\"Eurojuris Espa\u00f1a\",\"description\":\"Despachos abogados\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/#\\\/schema\\\/person\\\/866ab2797ce71a5b3051467560ee28ed\",\"name\":\"Laura\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g\",\"caption\":\"Laura\"},\"sameAs\":[\"http:\\\/\\\/\"],\"url\":\"http:\\\/\\\/www.asociacion-eurojuris.es\\\/en\\\/author\\\/laura\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Die rolle der Anwalt","description":"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/","og_locale":"en_US","og_type":"article","og_title":"Die rolle der Anwalt","og_description":"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.","og_url":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/","og_site_name":"Eurojuris Espa\u00f1a","article_published_time":"2012-01-19T08:00:30+00:00","article_modified_time":"2020-04-11T07:20:36+00:00","author":"Laura","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Laura","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/#article","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/"},"author":{"name":"Laura","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"headline":"Die Rolle des Anwalts beim Verkauf von Immobilien","datePublished":"2012-01-19T08:00:30+00:00","dateModified":"2020-04-11T07:20:36+00:00","mainEntityOfPage":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/"},"wordCount":726,"keywords":["deutschsprachige rechtsanw\u00e4lte spanien","Eurojuris Espa\u00f1a","immobilien kaufvertrages spanien","immobilienkauf beratung","immobilientransaktionen spanien","immobilienverkauf beratung spanien","insolvezrecht spanien","it recht spanien","juristen spanien","prozessrecht spanien","rechtsanw\u00e4lte tarragona","spanische rechtsanw\u00e4lte","tarracoiuris rechtsanw\u00e4lte"],"articleSection":["Ver\u00f6ffentichungen"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/","url":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/","name":"Die rolle der Anwalt","isPartOf":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website"},"datePublished":"2012-01-19T08:00:30+00:00","dateModified":"2020-04-11T07:20:36+00:00","author":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed"},"description":"Die Juristen spielen eine wesentliche Rolle in der Beratung von K\u00e4ufern, damit diese Eigentum von Inmobilien mit voller Garantie erwerben k\u00f6nnen.","breadcrumb":{"@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/die-rolle-des-anwalts-beim-verkauf-von-immobilien\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.asociacion-eurojuris.es\/en\/"},{"@type":"ListItem","position":2,"name":"Die Rolle des Anwalts beim Verkauf von Immobilien"}]},{"@type":"WebSite","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#website","url":"https:\/\/www.asociacion-eurojuris.es\/en\/","name":"Eurojuris Espa\u00f1a","description":"Despachos abogados","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.asociacion-eurojuris.es\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.asociacion-eurojuris.es\/en\/#\/schema\/person\/866ab2797ce71a5b3051467560ee28ed","name":"Laura","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/6ca21eb9a8ee5bb4943b9ea0c89b66fa6c2281f92a8f3f7b205e0a49ddcca58c?s=96&d=blank&r=g","caption":"Laura"},"sameAs":["http:\/\/"],"url":"http:\/\/www.asociacion-eurojuris.es\/en\/author\/laura\/"}]}},"_links":{"self":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/1443","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/comments?post=1443"}],"version-history":[{"count":5,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/1443\/revisions"}],"predecessor-version":[{"id":6338,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/posts\/1443\/revisions\/6338"}],"wp:attachment":[{"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/media?parent=1443"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/categories?post=1443"},{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/www.asociacion-eurojuris.es\/en\/wp-json\/wp\/v2\/tags?post=1443"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}